{"id":5889,"date":"2020-12-25T20:15:23","date_gmt":"2020-12-26T01:15:23","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=5889"},"modified":"2020-12-25T20:16:01","modified_gmt":"2020-12-26T01:16:01","slug":"la-educacion-superior-virtual-seria-una-realidad-en-unos-cinco-anos","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/la-educacion-superior-virtual-seria-una-realidad-en-unos-cinco-anos\/","title":{"rendered":"La educaci\u00f3n superior virtual ser\u00eda una realidad en unos cinco a\u00f1os"},"content":{"rendered":"\n<p><strong>Una encuesta a nivel mundial, presentada por Ipsos, en estudio para el <a href=\"https:\/\/es.weforum.org\/\" class=\"ek-link\">Foro Econ\u00f3mico Mundial<\/a>, revela las expectativas respecto al costo de educaci\u00f3n, modalidad de ense\u00f1anza, y el futuro de la educaci\u00f3n superior. <\/strong><\/p>\n\n\n\n<p>Debido a la pandemia del <a href=\"https:\/\/news.google.com\/covid19\/map?hl=es-419&amp;gl=PE&amp;ceid=PE%3Aes-419\" class=\"ek-link\">COVID 19<\/a>, la virtualizaci\u00f3n de las clases ha sido la medida usada para no parar con los estudios, universidades en todo optaron por la educaci\u00f3n remota. El estudio realizado por <a href=\"https:\/\/www.ipsos.com\/es-es\" class=\"ek-link\">Ipsos<\/a>, a adultos menores de 75 a\u00f1os, de ambos g\u00e9neros, y de 29 pa\u00edses; revela que un 23% espera que la educaci\u00f3n sea completamente virtual y solo un 49% &nbsp;espera que sea tanto presencial como virtual o solo virtual.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"545\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/Ipsos-5-1024x545.png\" alt=\"\" class=\"wp-image-5909\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/Ipsos-5-1024x545.png 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/Ipsos-5-300x160.png 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/Ipsos-5-768x409.png 768w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/Ipsos-5.png 1182w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Fuente: <a href=\"https:\/\/www.ipsos.com\/sites\/default\/files\/ct\/news\/documents\/2020-11\/higher-education-in-person-or-online.pdf\" class=\"ek-link\">Ipsos <\/a><\/figcaption><\/figure>\n\n\n\n<p>Gran parte de Asia y \u00c1frica cree que la educaci\u00f3n se impartir\u00eda solo o mayoritariamente online. En Jap\u00f3n y China, la mitad cree que la educaci\u00f3n remota se mantendr\u00eda. Adem\u00e1s, un gran porcentaje, del 36% cree que el costo de la educaci\u00f3n presencial vale la pena, frente a un 36% que no lo cree necesario. Espec\u00edficamente en el caso de Per\u00fa, un 49% piensa que el costo de una educaci\u00f3n superior presencial vale la pena, frente a un 44%. <\/p>\n\n\n\n<p>El estudio revela tambi\u00e9n, que los adultos de 50 a 74\na\u00f1os, un 55%, y de este un 59%, quienes poseen un t\u00edtulo universitario, est\u00e1n de\nacuerdo con que la educaci\u00f3n superior sea presencial, y que su costo vale la\npena. Pa\u00edses como China, Suecia, Arabia Saudita, Germania, Polonia, se muestras\nrenuentes a creer que la educaci\u00f3n virtual presencial no valdr\u00eda el costo de\npago. Por otro lado, pa\u00edses como Corea del Sur, Chile, Italia, Estados Unidos,\nEspa\u00f1a, Rusia, Brasil, no cree que el costo valdr\u00eda la pena, mismos que esperan\nque la educaci\u00f3n virtual superior sea mayoritaria. <\/p>\n\n\n\n<p>A esto, se suma tambi\u00e9n una encuesta de Ipsos, <a href=\"https:\/\/www.ipsos.com\/sites\/default\/files\/ct\/news\/documents\/2020-10\/6253520inf_v3_15oct20_002.pdf\" class=\"ek-link\">\u201cPensando en los estudiantes, \u00bfC\u00f3mo nos preparamos para el 2021?\u201d<\/a>, en el que se califica en rol de las universidades estatales con un 22% y a las privadas con un 52%. Lo que invita a hacer an\u00e1lisis respecto al valor de la educaci\u00f3n superior y la gesti\u00f3n de estas. <\/p>\n\n\n\n<p>En lo que va del a\u00f1o, la educaci\u00f3n superior ha sido completamente virtual, el ministro de educaci\u00f3n, Ricardo Cuenca, <a href=\"https:\/\/gestion.pe\/peru\/ministerio-de-educacion-clases-en-universidades-seguirian-siendo-virtuales-en-2021-minedu-ricardo-cuenca-nndc-noticia\/\" class=\"ek-link\">anunci\u00f3 que durante el a\u00f1o 2021 tambi\u00e9n habr\u00edan clases virtuales <\/a>y solo se usar\u00edan las instalaciones universitarias para el uso de laboratorios, lo que parece indicar que esta modalidad se complementar\u00eda a la presencial. A\u00fan est\u00e1 por verse. <\/p>\n\n\n\n<p>Por: Alondra Quiroz. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una encuesta a nivel mundial, presentada por Ipsos, en estudio para el Foro Econ\u00f3mico Mundial, revela las expectativas respecto al costo de educaci\u00f3n, modalidad de ense\u00f1anza, y el futuro de la educaci\u00f3n superior. Debido a la pandemia del COVID 19, la virtualizaci\u00f3n de las clases ha sido la medida usada para no parar con los [&hellip;]<\/p>\n","protected":false},"author":69,"featured_media":5912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[27,39,360],"tags":[558,86,679],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5889"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=5889"}],"version-history":[{"count":3,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5889\/revisions"}],"predecessor-version":[{"id":6357,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/5889\/revisions\/6357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/5912"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=5889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=5889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=5889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}