{"id":6013,"date":"2020-12-23T21:05:28","date_gmt":"2020-12-24T02:05:28","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=6013"},"modified":"2020-12-23T21:08:04","modified_gmt":"2020-12-24T02:08:04","slug":"el-gobierno-decreta-restricciones-para-evitar-el-contagio-en-fiestas-navidenas","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/el-gobierno-decreta-restricciones-para-evitar-el-contagio-en-fiestas-navidenas\/","title":{"rendered":"El gobierno decreta restricciones para evitar el contagio en fiestas navide\u00f1as"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong>Se deber\u00e1n acatar las medidas establecidas por el estado para evitar la propagaci\u00f3n del virus<\/strong><\/p>\n\n\n\n<p>En vista a celebrar las pr\u00f3ximas festividades como navidad y a\u00f1o nuevo. El gobierno de Sagasti decret\u00f3 algunas restricciones que ayudar\u00edan a evitar la propagaci\u00f3n de contagios y una posible segunda ola. Debido a que resultan ser d\u00edas en los que se pasa en familia e inclusive con numerosa cantidad de personas. Esto podr\u00eda convertirse en un foco infeccioso, pero se deber\u00eda evitar, ya que el n\u00famero de infectados y fallecidos sigue en aumento.\u00a0  <\/p>\n\n\n\n<p>El 16 de diciembre se estableci\u00f3 bajo el <a href=\"https:\/\/busquedas.elperuano.pe\/normaslegales\/decreto-supremo-que-restringe-el-transito-de-vehiculos-parti-decreto-supremo-n-194-2020-pcm-1912705-4\/\">Decreto supremo N\u00b0 194-2020-PCM<\/a> la restricci\u00f3n del tr\u00e1nsito de veh\u00edculos particulares en los d\u00edas 24,25 y 31 de diciembre y 1 enero del 2021. La sanci\u00f3n para quienes la infrinjan ser\u00e1 el pago de una papeleta valorizada en <strong>S\/6.450<\/strong>. Las personas que deseen movilizarse por esas fechas tendr\u00e1n que hacerlo mediante transporte p\u00fablico, ya sea buses, taxis, el metropolitano; as\u00ed como transporte no motorizado.<br><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/Pilar-mazzeti-1024x683.jpg\" alt=\"\" class=\"wp-image-6031\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/Pilar-mazzeti-1024x683.jpg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/Pilar-mazzeti-300x200.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/Pilar-mazzeti-768x512.jpg 768w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/Pilar-mazzeti.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foto de la ministra de salud Pilar Mazzeti. Fuente: Andina<\/figcaption><\/figure>\n\n\n\n<p> El d\u00eda 21 de diciembre la ministra de salud Pilar Mazzeti anunci\u00f3 el toque de queda en<strong> Lima <\/strong>y<strong> Callao<\/strong> que ser\u00e1 impuesto desde el 22 de diciembre hasta el 4 de enero del 2021. Desde las <strong>11:00 pm<\/strong> hasta <strong>4:00 am<\/strong> del siguiente d\u00eda. Otras regiones como Tumbes, Piura, La Libertad y la provincia del Santa, en \u00c1ncash comenzar\u00e1n a partir de las <strong>10:00 pm<\/strong> hasta <strong>4:00 am<\/strong> del d\u00eda siguiente. Todo ello qued\u00f3 establecido en el <a href=\"https:\/\/busquedas.elperuano.pe\/normaslegales\/decreto-supremo-que-prorroga-el-estado-de-emergencia-naciona-decreto-supremo-n-201-2020-pcm-1914076-2\/\">Decreto supremo N\u00ba 201-2020-PCM<\/a>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se deber\u00e1n acatar las medidas establecidas por el estado para evitar la propagaci\u00f3n del virus En vista a celebrar las pr\u00f3ximas festividades como navidad y a\u00f1o nuevo. El gobierno de Sagasti decret\u00f3 algunas restricciones que ayudar\u00edan a evitar la propagaci\u00f3n de contagios y una posible segunda ola. Debido a que resultan ser d\u00edas en los [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":6021,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[329,359,33],"tags":[166,196],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6013"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=6013"}],"version-history":[{"count":3,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6013\/revisions"}],"predecessor-version":[{"id":6037,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6013\/revisions\/6037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/6021"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=6013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=6013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=6013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}