{"id":6033,"date":"2020-12-23T22:56:59","date_gmt":"2020-12-24T03:56:59","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=6033"},"modified":"2021-01-06T18:25:38","modified_gmt":"2021-01-06T23:25:38","slug":"el-art-rock-en-la-musica-de-radiohead","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/el-art-rock-en-la-musica-de-radiohead\/","title":{"rendered":"El &#8216;art rock&#8217; en la m\u00fasica de Radiohead"},"content":{"rendered":"\n<p><strong>Por d\u00e9cadas, el rock -como cualquier otro g\u00e9nero- ha ido teniendo altas y bajas en cuanto a su acreditaci\u00f3n como g\u00e9nero musical \u00abserio\u00bb e \u00abimportante\u00bb. Sin embargo, a finales de los &#8217;90s, esto dejar\u00eda de estar en debate con la llegada y posterior evoluci\u00f3n de Radiohead.<\/strong><\/p>\n\n\n\n<p>Durante la d\u00e9cada de los ochenta, uno de los subg\u00e9neros del rock se llev\u00f3 al \u00e1mbito<em> mainstream<\/em> en una forma que el p\u00fablico dej\u00f3 de seguirlo: el <em>hair metal<\/em>, que retrataba una mezcla de glam rock, pop y heavy metal. Mientras, el pop tomaba mayor influencia en la vida cotidiana de las personas; pero la llegada de los &#8217;90s supuso un cambio paradigm\u00e1tico, en tanto bandas como Oasis o Blur maximizaban la expansi\u00f3n del britpop. Paralelamente, Radiohead ven\u00eda publicando dos \u00e1lbumes durante 1993 y 1995; sin embargo, fue en 1997 con &#8216;<a href=\"https:\/\/open.spotify.com\/album\/6dVIqQ8qmQ5GBnJ9shOYGE\" class=\"ek-link\">OK Computer<\/a>&#8216; que llev\u00f3 al g\u00e9nero a su c\u00faspide art\u00edstica. <\/p>\n\n\n\n<p>Una percusi\u00f3n hipn\u00f3tica, riffs reverberados, bajo saturado a niveles sint\u00e9ticos, solos con tintes el\u00e9ctricos de la mano de Jonny Greenwood, y una <em>performance<\/em> y l\u00edrica por parte de Thom Yorke que retrataba la anticipaci\u00f3n social, mundial e \u00edntima hacia el inminente cambio milenario. El rock que emanaba de las canciones ameritaban <strong>composiciones m\u00e1s complejas, una vasta conceptualizaci\u00f3n filos\u00f3fica y adiciones est\u00e9ticas<\/strong> propias de la banda. Basta notar todo lo mencionado en canciones como <em>Paranoid Android<\/em>, <em>Exit Music (For A Film)<\/em>, <em>Let Down<\/em> o <em>The Tourist<\/em>.<\/p>\n\n\n\n<p>Asimismo, estos patrones musicales que asemejaban una virtud art\u00edstica se hizo una constante en todos sus \u00e1lbumes posteriores. &#8216;Kid A&#8217;, publicado en el 2000, fue todo un hito en la historia de la m\u00fasica por mostrar la metamorfosis de una banda que hab\u00eda alcanzado la cima. Este \u00e1lbum se torn\u00f3, en esencia, <strong>electr\u00f3nico<\/strong> -pero con el rock como piedra angular- y con variantes tem\u00e1ticas de la tecnolog\u00eda en un mundo dist\u00f3pico, junto con el uso de sintetizadores, <a href=\"https:\/\/es.wikipedia.org\/wiki\/Vocoder\" class=\"ek-link\">vocoder<\/a>, y dem\u00e1s instrumentos novedosos que iban contra la escena musical popular. No tuvo ning\u00fan videoclip promocional, m\u00e1s que fragmentos audiovisuales regados por la incipiente web: Radiohead hizo todo lo contrario a seguir en la fama.<\/p>\n\n\n\n<p>El camino se fue repitiendo. &#8216;Amnesiac&#8217; del 2001 continu\u00f3 con la vertiente electr\u00f3nica, pero a\u00f1adi\u00f3 al <strong>jazz<\/strong> como g\u00e9nero complementario. &#8216;In Rainbows&#8217; (2007) por su parte recobr\u00f3 la espiritualidad vista 10 a\u00f1os antes: la banda tom\u00f3 la decisi\u00f3n de mostrar un sonido crudo, <strong>arreglos atemporales<\/strong> y letras que iban en torno a reflexiones rom\u00e1nticas-depresivas. &#8216;A Moon Shaped Pool&#8217; del 2016 es el m\u00e1s reciente, pero a la vez, el m\u00e1s sentimental de todos: la incorporaci\u00f3n de <strong>orquesta musical<\/strong> dota de una teatralidad <em><a href=\"https:\/\/es.wikipedia.org\/wiki\/Sui_g%C3%A9neris\" class=\"ek-link\">sui generis<\/a><\/em>.<\/p>\n\n\n\n<p>Una teatralidad art\u00edstica en el g\u00e9nero que no se ha visto antes en la historia de la m\u00fasica, y que es poco probable que se vuelva a repetir. Un &#8216;art rock&#8217; (rock art\u00edstico) que mostr\u00f3 la prevalencia del g\u00e9nero como algo fundamental.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por d\u00e9cadas, el rock -como cualquier otro g\u00e9nero- ha ido teniendo altas y bajas en cuanto a su acreditaci\u00f3n como g\u00e9nero musical \u00abserio\u00bb e \u00abimportante\u00bb. Sin embargo, a finales de los &#8217;90s, esto dejar\u00eda de estar en debate con la llegada y posterior evoluci\u00f3n de Radiohead. Durante la d\u00e9cada de los ochenta, uno de los [&hellip;]<\/p>\n","protected":false},"author":75,"featured_media":6040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[46,34],"tags":[67,170,897,865],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6033"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=6033"}],"version-history":[{"count":4,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6033\/revisions"}],"predecessor-version":[{"id":6044,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6033\/revisions\/6044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/6040"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=6033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=6033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=6033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}