{"id":6148,"date":"2020-12-24T13:51:40","date_gmt":"2020-12-24T18:51:40","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=6148"},"modified":"2021-01-07T10:37:23","modified_gmt":"2021-01-07T15:37:23","slug":"san-juan-de-lurigancho-jovenes-amantes-de-la-danza-en-tiempos-de-pandemia","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/san-juan-de-lurigancho-jovenes-amantes-de-la-danza-en-tiempos-de-pandemia\/","title":{"rendered":"San Juan de Lurigancho: J\u00f3venes amantes de la danza en tiempos de pandemia"},"content":{"rendered":"\n<p><strong>La agrupaci\u00f3n folcl\u00f3rica de todas las artes <\/strong><a aria-label=\"Llapan Yaguar (opens in a new tab)\" rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/A.F.T.A.LlapanYawar\" target=\"_blank\" class=\"ek-link\"><strong>Llapan yawar <\/strong><\/a><strong>es un grupo folcl\u00f3rico de Campoy, San Juan de Lurigancho, que re\u00fane a chicos y chicas en torno a la cultura y la danza. El pasado 20 de diciembre, luego de meses de pare en sus actividades, realizaron su primer evento cultural. <\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"473\" height=\"340\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/18.png\" alt=\"\" class=\"wp-image-6156\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/18.png 473w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/18-300x216.png 300w\" sizes=\"(max-width: 473px) 100vw, 473px\" \/><figcaption>J\u00f3venes en el juego de parejas de la danza Kullawada<br>Fotograf\u00eda: Jhared V\u00e1squez<\/figcaption><\/figure><\/div>\n\n\n\n<p>Un elenco de j\u00f3venes liderado por el profesor de danzas Enrique Hern\u00e1ndez y Gabriel Leandro, integrantes activos en la comunidad campoyana, realizaron un show folcl\u00f3rico como clausura de sus recientemente reanudadas actividades art\u00edsticas. El evento se realiz\u00f3 en <a href=\"https:\/\/es.wikipedia.org\/wiki\/Distrito_de_San_Juan_de_Lurigancho\" class=\"ek-link\">C<\/a><a aria-label=\"ampoy (opens in a new tab)\" rel=\"noreferrer noopener\" href=\"https:\/\/es.wikipedia.org\/wiki\/Distrito_de_San_Juan_de_Lurigancho\" target=\"_blank\" class=\"ek-link\">ampoy<\/a>, San Juan de Lurigancho, y tuvo una duraci\u00f3n de cuatro horas. \u00a0<\/p>\n\n\n\n<p>Un total de 25 j\u00f3venes, pertenecientes a la comunidad de Campoy, participaron como bailarines durante la presentaci\u00f3n que constituy\u00f3 la clausura de dos meses de ensayos semanales y ardua preparaci\u00f3n.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"561\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/MG_0134-gausianno-1.png\" alt=\"\" class=\"wp-image-6164\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/MG_0134-gausianno-1.png 561w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/MG_0134-gausianno-1-300x200.png 300w\" sizes=\"(max-width: 561px) 100vw, 561px\" \/><figcaption>Integrante de Llapan Yaguar usando una camiseta con la frase: \u00abConfieso que soy adicta a la danza y no pienso rehabilitarme\u00bb.<br>Fotograf\u00eda: Jhared Vasquez<\/figcaption><\/figure><\/div>\n\n\n\n<p>El programa del evento consisti\u00f3 en la presentaci\u00f3n de cuatro danzas: <a href=\"https:\/\/resenasdanzasperu.blogspot.com\/2017\/11\/diablicos-de-tucume-lambayeque.html\" target=\"_blank\" aria-label=\"Los diablicos de T\u00facume (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"ek-link\">Los diablicos de T\u00facume<\/a>, danza virreinal de car\u00e1cter religiosa perteneciente a Lambayeque,<a aria-label=\" Son de los diablos (opens in a new tab)\" href=\"https:\/\/resenasdanzasperu.blogspot.com\/2014\/07\/danza-son-de-los-diablos-callao-lima.html\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\"> Son de los diablos<\/a>, danza afroperuana, <a href=\"https:\/\/es.wikipedia.org\/wiki\/Kullawada\" class=\"ek-link\">Kullawada<\/a>, danza aymara y <a aria-label=\"Ani xeati (opens in a new tab)\" href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;ved=2ahUKEwih3O2NgOftAhWUDrkGHck9ANoQFjACegQIBxAC&amp;url=https%3A%2F%2Fwww.raptravel.org%2Fdanzas-del-peru%2Fdanza-ani-sheati-de-comunidades-nativas-shipibos-conibos-de-ucayali.php&amp;usg=AOvVaw14WItBSWxUe65_1S7dQ28R\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\">Ani xeati<\/a>, danza perteneciente a la cultura conibo shipibo. Algunos objetos del colorido vestuario fueron hechos de material reciclado y elaborados por los mismos danzantes. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"510\" height=\"340\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/11.png\" alt=\"\" class=\"wp-image-6167\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/11.png 510w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2020\/12\/11-300x200.png 300w\" sizes=\"(max-width: 510px) 100vw, 510px\" \/><figcaption>M\u00e1scara de la danza Los diablicos de T\u00facume hecha de material reciclado. <br>Fotograf\u00eda: Jhared V\u00e1squez <\/figcaption><\/figure><\/div>\n\n\n\n<p>Manteniendo los <a href=\"http:\/\/www.minsa.gob.pe\/covid-19\/\" target=\"_blank\" aria-label=\"protocolos de sanidad establecidos por el MINSA (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"ek-link\">protocolos de sanidad establecidos por el MINSA<\/a>, todos los asistentes e incluso los bailarines portaban mascarillas. El p\u00fablico asistente fue ubicado en espacios demarcados para respetar el distanciamiento social y el aforo fue limitado. <\/p>\n\n\n\n<p>Con el inicio de la pandemia, esta agrupaci\u00f3n de danzas tuvo que suspender sus ensayos y cancelar presentaciones en varios eventos folcl\u00f3ricos dentro y fuera de Lima. No obstante, durante el confinamiento, los integrantes aprovecharon las nuevas modalidades de comunicaci\u00f3n virtual para realizar un peque\u00f1o <a href=\"https:\/\/youtu.be\/VT4xJWySlJ4\" target=\"_blank\" aria-label=\"concurso de videos cortos.  (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"ek-link\">concurso de videos cortos. <\/a><\/p>\n\n\n\n<p><strong>Tras la realizaci\u00f3n de esta actividad, Llapan Yaguar reafirma, una vez m\u00e1s en sus once a\u00f1os de vida institucional,  su presencia como actor social y cultural dentro de la comunidad de San Juan de Lurigancho<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La agrupaci\u00f3n folcl\u00f3rica de todas las artes Llapan yawar es un grupo folcl\u00f3rico de Campoy, San Juan de Lurigancho, que re\u00fane a chicos y chicas en torno a la cultura y la danza. El pasado 20 de diciembre, luego de meses de pare en sus actividades, realizaron su primer evento cultural. Un elenco de j\u00f3venes [&hellip;]<\/p>\n","protected":false},"author":96,"featured_media":6174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[34,554,314,324],"tags":[81,62,722,252],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6148"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/96"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=6148"}],"version-history":[{"count":4,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6148\/revisions"}],"predecessor-version":[{"id":6339,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6148\/revisions\/6339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/6174"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=6148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=6148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=6148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}