{"id":6340,"date":"2020-12-25T19:49:53","date_gmt":"2020-12-26T00:49:53","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=6340"},"modified":"2020-12-25T19:49:55","modified_gmt":"2020-12-26T00:49:55","slug":"ediciones-altazor-a-la-vanguardia-del-comic-peruano","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/ediciones-altazor-a-la-vanguardia-del-comic-peruano\/","title":{"rendered":"Ediciones Altazor a la vanguardia del c\u00f3mic peruano"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.facebook.com\/ediciones.altazor\" class=\"ek-link\">Ediciones Altazor<\/a>, una editorial peruana con m\u00e1s de 25 a\u00f1os en el mercado est\u00e1 siendo la vanguardia del c\u00f3mic peruano en la actualidad, con m\u00e1s de 5 obras publicadas de autores peruanos, la m\u00e1s representativa es la del autor Ricardo Lazo y su obra: <a href=\"https:\/\/www.facebook.com\/ElmundodeWayra\" class=\"ek-link\">Wayra<\/a>.<br><\/p>\n\n\n\n<p>El contexto de los c\u00f3mic peruanos es de un lugar con dif\u00edcil avance principalmente para los nuevos proyectos puesto que si bien se tiene la intenci\u00f3n, los proyectos fracasan por una falta de log\u00edstica y capital del cual no tantos quieren invertir al ver el negocio del c\u00f3mic peruano como uno no redituable, sin embargo la Editorial Altazor est\u00e1 cambiando este oscuro panorama con ya varias publicaciones y apoyo a los artistas, d\u00e1ndole un espacio donde su trabajo se pueda editar, publicar y recibir r\u00e9dito.<br><\/p>\n\n\n\n<p>Altazor aparece en un buen momento con sus principales publicaciones en 2019 cuando empezaban a aparecer s\u00edntomas de las bases de una futura industria del c\u00f3mic, con muchas publicaciones de parte de otras editoriales as\u00ed como publicaciones propias o muchos concursos y eventos que difunden la cultura, sin embargo muchos de estos proyectos fueron truncados por la pandemia pero que sin embargo no ha frenado los planes Ediciones Altazor y sus planes, como por ejemplo su \u00faltima publicaci\u00f3n: <a href=\"https:\/\/www.facebook.com\/alartsmayorca\" class=\"ek-link\">Caim\u00e1n, laguna de problemas<\/a> y <a href=\"https:\/\/www.facebook.com\/Patata-Comic-600278133963903\/\" class=\"ek-link\">Patata \u00a1Mi diario de dibujo!<\/a><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ediciones Altazor, una editorial peruana con m\u00e1s de 25 a\u00f1os en el mercado est\u00e1 siendo la vanguardia del c\u00f3mic peruano en la actualidad, con m\u00e1s de 5 obras publicadas de autores peruanos, la m\u00e1s representativa es la del autor Ricardo Lazo y su obra: Wayra. El contexto de los c\u00f3mic peruanos es de un lugar [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":6341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[46,34,44],"tags":[750,749,747],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6340"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=6340"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6340\/revisions"}],"predecessor-version":[{"id":6342,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6340\/revisions\/6342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/6341"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=6340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=6340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=6340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}