{"id":6462,"date":"2021-01-06T09:55:52","date_gmt":"2021-01-06T14:55:52","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=6462"},"modified":"2021-01-06T09:55:55","modified_gmt":"2021-01-06T14:55:55","slug":"elecciones-2021-se-triplicaran-los-locales-de-votacion","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/elecciones-2021-se-triplicaran-los-locales-de-votacion\/","title":{"rendered":"Elecciones 2021: Se triplicar\u00e1n los locales de votaci\u00f3n"},"content":{"rendered":"\n<p> Las elecciones del pr\u00f3ximo a\u00f1o se desarrollar\u00e1n en medio de la emergencia sanitaria por <a href=\"https:\/\/www.who.int\/es\/emergencies\/diseases\/novel-coronavirus-2019\" class=\"ek-link\">el nuevo coronavirus<\/a>, por lo cual, la <a href=\"https:\/\/www.onpe.gob.pe\/\">ONPE<\/a> ha anunciado las medidas sanitarias que se tomar\u00e1n para evitar un contagio masivo.  <\/p>\n\n\n\n<p>Los protocolos para este pr\u00f3ximo 11 de abril&nbsp; se publicaron mediante la<a href=\"https:\/\/cdn.www.gob.pe\/uploads\/document\/file\/1414959\/RJ-382-2020-JN.pdf.pdf\"> Resoluci\u00f3n Jefatural 000382-2020-JN\/ONPE<\/a>, fue aprobada por la Gerencia de Organizaci\u00f3n Electoral y Coordinaci\u00f3n Regional (GOECOR). La publicaci\u00f3n hecha mediante el diario oficial <a href=\"https:\/\/elperuano.pe\/\">El Peruano<\/a> dispone las medidas de bioseguridad en las Direcciones de la Oficina Descentralizada de Procesos Electorales (ODPE) y Oficinas Regionales de Coordinaci\u00f3n (ORC). En el documento se precisan protocolos para el local de votaci\u00f3n, para el personal antes del ingreso al local, la organizaci\u00f3n de los documentos y equipos electorales y dem\u00e1s procesos que se ejecuten ese d\u00eda<\/p>\n\n\n\n<p>\n\nEntre las medidas m\u00e1s resaltantes est\u00e1 que se triplicar\u00e1n&nbsp; los locales de votaci\u00f3n. Se suman a los colegios, normalmente usados, estadios, piscinas, plazas de toros y dem\u00e1s lugares abiertos. Ser\u00e1n m\u00e1s de 700 locales extras a los que normalmente se brindaban. Tambi\u00e9n los electores podr\u00e1n elegir su lugar de votaci\u00f3n seg\u00fan el local que se les acomode m\u00e1s, esto estar\u00e1 habilitado solo hasta fines del presente a\u00f1o. Se puede escoger hasta 3 locales y el 28 de enero de 2021 el sistema te indicar\u00e1 mediante correo electr\u00f3nico en cu\u00e1l de esos locales votar\u00e1s.\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las elecciones del pr\u00f3ximo a\u00f1o se desarrollar\u00e1n en medio de la emergencia sanitaria por el nuevo coronavirus, por lo cual, la ONPE ha anunciado las medidas sanitarias que se tomar\u00e1n para evitar un contagio masivo. Los protocolos para este pr\u00f3ximo 11 de abril&nbsp; se publicaron mediante la Resoluci\u00f3n Jefatural 000382-2020-JN\/ONPE, fue aprobada por la Gerencia [&hellip;]<\/p>\n","protected":false},"author":68,"featured_media":6962,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[359,33],"tags":[166,89],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6462"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=6462"}],"version-history":[{"count":3,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6462\/revisions"}],"predecessor-version":[{"id":6964,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6462\/revisions\/6964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/6962"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=6462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=6462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=6462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}