{"id":6776,"date":"2021-01-05T09:49:35","date_gmt":"2021-01-05T14:49:35","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=6776"},"modified":"2021-01-05T09:49:37","modified_gmt":"2021-01-05T14:49:37","slug":"la-sonoterapia-una-gran-alternativa","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/la-sonoterapia-una-gran-alternativa\/","title":{"rendered":"La sonoterapia: una gran alternativa"},"content":{"rendered":"\n<p>Con el avance del tiempo y la constante\nb\u00fasqueda del bienestar f\u00edsico y espiritual, siempre aparecen nuevas terapias\npara sanar. Existen muchos tipos de terapia, sin embargo, la sonoterapia ha\nestado cobrando fama en los \u00faltimos a\u00f1os, a pesar de que esta venga de haces\nmuchos a\u00f1os atr\u00e1s.<\/p>\n\n\n\n<p><a href=\"https:\/\/mejorconsalud.as.com\/sonoterapia-en-que-consiste\/\" class=\"ek-link\">La sonoterapia o terapia del sonido<\/a> es una tem\u00e1tica muy antigua que hace uso de la voz e instrumentos musicales para producir determinadas vibraciones que influyen beneficiosamente en nuestro organismo.<\/p>\n\n\n\n<p>Como el cuerpo est\u00e1 compuesto de vibraciones\nque vibran, valga la redundancia, a cierta frecuencia, lo que hace la terapia\ndel sonido es restaurar y corregir la frecuencia de resonancia correcta\ndevolviendo la salud a nuestras partes enfermas.<\/p>\n\n\n\n<p>En la sonoterapia se trabaja con la vibraci\u00f3n y\nno solamente con la m\u00fasica, como muchos creen. Es m\u00e1s, esta terapia tiene una\nbase cient\u00edfica la cual es el principio de la resonancia en simpat\u00eda, la cual\nsostiene que un objeto vibrante provoca vibraciones en otro objeto.<\/p>\n\n\n\n<p>B\u00e1sicamente, la terapia del sonido consiste en\nla aplicaci\u00f3n de la voz e instrumentos musicales y vibratorios en los campos\nenerg\u00e9ticos y sobre el cuerpo f\u00edsico, ya que el cuerpo humano es energ\u00eda. El uso\ndel sonido viene desde la creaci\u00f3n del ser humano para expresar informaci\u00f3n sobre\nel mundo que los rodea, comunicarse y para sanar. Es una de las terapias m\u00e1s\nantiguas del mundo.<\/p>\n\n\n\n<p>Como ya se explic\u00f3, el uso del sonido viene de\nmuchos a\u00f1os atr\u00e1s, sin embargo siempre ha estado limitado a un campo espiritual\ny esot\u00e9rico. Pero en los \u00faltimos a\u00f1os se ha convertido en una modalidad terap\u00e9utica\nde car\u00e1cter cient\u00edfico y m\u00e9dico.<\/p>\n\n\n\n<p>Todo el universo est\u00e1 en estado de vibraci\u00f3n.\nEsto tambi\u00e9n incluye el cuerpo humano. Desde la c\u00e9lula m\u00e1s simple hasta el\n\u00f3rgano m\u00e1s complejo tiene un campo energ\u00e9tico y una raz\u00f3n vibratoria sana.<\/p>\n\n\n\n<p>Los instrumentos m\u00e1s usados en la sonoterapia\nson la voz (el m\u00e1s poderoso y eficaz), los cuencos tibetanos, diapasones terap\u00e9uticos,\ntambores oce\u00e1nicos, campanas, entre otros.<\/p>\n\n\n\n<p>La terapia del sonido provoca estados profundos\nde relajaci\u00f3n, armoniza los hemisferios cerebrales, limpia y equilibra el\nsistema energ\u00e9tico, alivia el dolor e incomodidades f\u00edsicas, alivia el estr\u00e9s,\nla tensi\u00f3n e hipertensi\u00f3n, calma las emociones y en algunos casos ha llegado a\nreducir significativamente tumores o c\u00e1ncer.<\/p>\n\n\n\n<p>&nbsp;Finalmente\ncabe resaltar que la sonoterapia cada vez se est\u00e1 usando m\u00e1s como terapia\ncomplementaria con resultados exitosos. Siempre es bueno consultar con el personal\nde salud para el tratamiento m\u00e1s \u00f3ptimo, sin embargo tambi\u00e9n es bueno ver otras\nalternativas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el avance del tiempo y la constante b\u00fasqueda del bienestar f\u00edsico y espiritual, siempre aparecen nuevas terapias para sanar. Existen muchos tipos de terapia, sin embargo, la sonoterapia ha estado cobrando fama en los \u00faltimos a\u00f1os, a pesar de que esta venga de haces muchos a\u00f1os atr\u00e1s. La sonoterapia o terapia del sonido es [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":6782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[30,482],"tags":[286,470,831],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6776"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=6776"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6776\/revisions"}],"predecessor-version":[{"id":6783,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6776\/revisions\/6783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/6782"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=6776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=6776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=6776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}