{"id":6844,"date":"2020-12-25T11:47:00","date_gmt":"2020-12-25T16:47:00","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=6844"},"modified":"2021-01-10T00:55:01","modified_gmt":"2021-01-10T05:55:01","slug":"1812-overture-de-tchaikovsky","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/1812-overture-de-tchaikovsky\/","title":{"rendered":"\u00ab1812 Overture\u00bb de Tchaikovsky"},"content":{"rendered":"\n<p style=\"text-align:justify\" class=\"has-mobile-text-align-justify\"><strong>La <\/strong><a class=\"ek-link\" href=\"https:\/\/www.youtube.com\/watch?v=1KzF1KgaREo\"><strong>\u201cObertura 1812\u201d<\/strong><\/a><strong> fue realizada en 1880 por <\/strong><a class=\"ek-link\" href=\"https:\/\/es.wikipedia.org\/wiki\/Piotr_Ilich_Chaikovski\"><strong>Piotr Ilich Tchaikovsky<\/strong><\/a><strong>, quien fue un compositor ruso nacido el 8 de mayo de 1840. Adem\u00e1s, realiz\u00f3 otras composiciones como: El lago de los cisnes\u00a0(1877), la \u00f3pera\u00a0Evgeny Oneguin\u00a0(1878) y\u00a0Capricho italiano\u00a0(1880).\u00a0<\/strong><\/p>\n\n\n\n<p style=\"text-align:justify\">Esta\ncomposici\u00f3n musical surge tras el inter\u00e9s del zar Alejandro II por rememorar la\nvictoria rusa frente a las tropas napole\u00f3nicas en 1812, para lo cual se propone\nla construcci\u00f3n de la catedral de Cristo Salvador en Mosc\u00fa. Este hecho conllev\u00f3\na la realizaci\u00f3n de una pieza que conmemore los hechos suscitados durante la\nguerra y as\u00ed poder ser interpretada el d\u00eda de la inauguraci\u00f3n de la catedral.<\/p>\n\n\n\n<p style=\"text-align:justify\">En\nun principio, los planes de Tchaikovsky para su composici\u00f3n inclu\u00edan una\ninterpretaci\u00f3n al aire libre en la plaza de la catedral, adem\u00e1s del sonido de\ncampanas y ca\u00f1ones que coordinen con la m\u00fasica; pero, lamentablemente, no se\npudo realizar de esta manera.<\/p>\n\n\n\n<p style=\"text-align:justify\">Esta pieza posee una gran carga significativa en la historia de Rusia, pues es una especie de narraci\u00f3n de la campa\u00f1a militar llevada a cabo por la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Grande_Arm%C3%A9e\" class=\"ek-link\">Grande Arm\u00e9e<\/a> de Napole\u00f3n Bonaparte en su invasi\u00f3n a tierras rusas y que, para desgracia de las tropas napole\u00f3nicas, terminaron en total fracaso.<\/p>\n\n\n\n<p style=\"text-align:justify\">La magn\u00edfica obra musical de P. Tchaikovsky comienza con una melod\u00eda rusa titulada \u201cDios proteja a su pueblo\u201d que, como se puede apreciar, es de \u00edndole religioso y simboliza el hecho de c\u00f3mo se dio a conocer al pueblo, en las congregaciones religiosas, la noticia de la guerra declarada entre Francia y Rusia, para ello se hace uso de violas y violonchelos.<\/p>\n\n\n\n<p style=\"text-align:justify\">Posteriormente,\nla armon\u00eda cambia con la incorporaci\u00f3n de flautas y oboes, adem\u00e1s de un ligero\naumento en la intensidad del ritmo como representaci\u00f3n de la angustia vivida\npor el pueblo ruso frente a la guerra.<\/p>\n\n\n\n<p style=\"text-align:justify\">La\narmon\u00eda cambia nuevamente con el sonido de los timbales acompa\u00f1ados por las\nr\u00e1pidas frecuencias de las cuerdas que, adem\u00e1s, est\u00e1n complementados por los\ndem\u00e1s instrumentos del resto de la orquesta. En esta parte se simbolizar\u00eda el\nllamado a la preparaci\u00f3n de la defensa del pueblo ruso.<\/p>\n\n\n\n<p style=\"text-align:justify\">La\ninvasi\u00f3n de los enemigos franceses se representa con una melod\u00eda de armon\u00eda\nintensa y t\u00e9trica bajo la implementaci\u00f3n de bajos y violonchelos.<\/p>\n\n\n\n<p style=\"text-align:justify\">Con el sonido de los tambores se introduce un fragmento del himno nacional de Francia, <a href=\"https:\/\/es.wikipedia.org\/wiki\/La_Marsellesa\" class=\"ek-link\">La Marsellesa<\/a>, como s\u00edmbolo de Napole\u00f3n Bonaparte e indicio del avance victorioso de sus tropas, pero hay que precisar que se utiliz\u00f3 por su vigencia durante el a\u00f1o de la creaci\u00f3n de la pieza musical en 1880, puesto que el a\u00f1o de la guerra este se encontraba prohibido.<\/p>\n\n\n\n<p style=\"text-align:justify\">Por\nun momento, la r\u00e1pida frecuencia y la mayor intensidad en las cuerdas\nrepresentan el contraataque ruso; sin embargo, vuelve a imponerse La Marsellesa\nque va disminuyendo su intensidad como representaci\u00f3n de una breve pausa de las\nacciones b\u00e9licas.<\/p>\n\n\n\n<p style=\"text-align:justify\">Se\nhace un llamado a la uni\u00f3n para la fortaleza del bando ruso mediante una\narmon\u00eda alegre conocida como \u201cu vorot\u201d, la cual rememorar\u00e1 la vida alegre del\npueblo ruso lejos de las guerras a trav\u00e9s del uso de flautas, clarinetes,\npanderetas y violonchelos, siguiendo un timbre agudo y ameno.<\/p>\n\n\n\n<p style=\"text-align:justify\">La\nmelod\u00eda de las cuerdas como representaci\u00f3n de los rusos y la melod\u00eda al ritmo de\nLa Marsellesa como representaci\u00f3n de las tropas de Napole\u00f3n chocan una y otra\nvez como simbolizaci\u00f3n del enfrentamiento, pero una vez m\u00e1s se impone la\nmelod\u00eda francesa.<\/p>\n\n\n\n<p style=\"text-align:justify\">Pese a todo, un momento crucial de la composici\u00f3n musical es el sonido de los 5 disparos de ca\u00f1ones como s\u00edmbolo del avance y desaf\u00edo de los rusos frente a las tropas napole\u00f3nicas en representaci\u00f3n de la batalla de Borodin\u00f3 el 7 de setiembre de 1812. A pesar de las constantes victorias de los franceses, comenzaron a decaer por la precaria condici\u00f3n que hab\u00edan adoptado teniendo al clima de invierno ruso en su contra.<\/p>\n\n\n\n<p style=\"text-align:justify\">Nuevamente se escucha la melod\u00eda religiosa del principio, \u201cDios proteja a su pueblo\u201d, pero esta vez con una armon\u00eda de car\u00e1cter triunfante como representaci\u00f3n de que las plegarias hechas por los rusos fueron escuchadas, para ello se hace uso de los sonidos de todos los instrumentos de la orquesta, as\u00ed como el de las campanas. <\/p>\n\n\n\n<p style=\"text-align:justify\">Por \u00faltimo, ya al final de la composici\u00f3n, se escucha la melod\u00eda del himno \u201cDios salve al Zar\u201d que es acompa\u00f1ado del sonido de las campanas y de 11 disparos de ca\u00f1\u00f3n que simbolizan el contraataque ruso que les permiti\u00f3 derrotar a los invasores franceses. Aqu\u00ed cabe precisar tambi\u00e9n que dicho himno se utiliz\u00f3 en la composici\u00f3n de esta pieza por su vigencia el a\u00f1o de creaci\u00f3n y no cuando sucedi\u00f3 la guerra. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>Bibliograf\u00eda:<\/p><cite>Olgu\u00edn \u00c1lvarez, J. (2020).  OBERTURA DE 1812 OP. 49, BREVE RESE\u00d1A HIST\u00d3RICA Y UNA GU\u00cdA DE AUDICI\u00d3N. <em>Revista de Marina, 137<\/em>(977), 43-48. <\/cite><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>La \u201cObertura 1812\u201d fue realizada en 1880 por Piotr Ilich Tchaikovsky, quien fue un compositor ruso nacido el 8 de mayo de 1840. Adem\u00e1s, realiz\u00f3 otras composiciones como: El lago de los cisnes\u00a0(1877), la \u00f3pera\u00a0Evgeny Oneguin\u00a0(1878) y\u00a0Capricho italiano\u00a0(1880).\u00a0 Esta composici\u00f3n musical surge tras el inter\u00e9s del zar Alejandro II por rememorar la victoria rusa frente [&hellip;]<\/p>\n","protected":false},"author":76,"featured_media":6862,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[46,34,44],"tags":[81,170],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6844"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/76"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=6844"}],"version-history":[{"count":7,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6844\/revisions"}],"predecessor-version":[{"id":7521,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6844\/revisions\/7521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/6862"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=6844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=6844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=6844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}