{"id":6849,"date":"2021-01-06T09:06:09","date_gmt":"2021-01-06T14:06:09","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=6849"},"modified":"2021-01-06T09:07:56","modified_gmt":"2021-01-06T14:07:56","slug":"el-poder-de-los-medios-de-comunicacion-en-la-politica","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/el-poder-de-los-medios-de-comunicacion-en-la-politica\/","title":{"rendered":"El poder de los medios de comunicaci\u00f3n en la pol\u00edtica"},"content":{"rendered":"\n<p style=\"text-align:justify\">Tanto la comunicaci\u00f3n como la pol\u00edtica est\u00e1n limitadas a ejercerse dentro de un determinado territorio, contexto o cultura para poder lograr un \u00f3ptimo desarrollo para con sus part\u00edcipes, de lo contrario ambos procesos terminar\u00edan siendo obsoletos, partiendo de esta premisa podemos observar  la relaci\u00f3n entre la comunicaci\u00f3n y la pol\u00edtica siendo ambas aplicables dentro del terreno de la otra y complement\u00e1ndose entre si para lograr sus objetivos.<\/p>\n\n\n\n<p>Como parte de la comunicaci\u00f3n los medios comunicativos han constituido una gran fuente de poner y contrapoder dentro del foco social. Esta lucha de poderes se ejerce dentro de la batalla por la opini\u00f3n p\u00fablica, ya que la manera en que la gente comprende y piensa delimita el futuro de las normas y valores que se manifiestan dentro de la sociedad. La prensa se ha convertido en una todopoderosa y a\u00fan m\u00e1s gracias a la potenciaci\u00f3n de la tecnolog\u00eda la cual ha permitido a los medios evolucionar en la pr\u00e1ctica.<\/p>\n\n\n\n<p style=\"text-align:justify\">En nuestra sociedad la pol\u00edtica es inevitablemente medi\u00e1tica, el funcionamiento del sistema pol\u00edtico se representa en los medios de comunicaci\u00f3n con la finalidad de obtener el apoyo o en menor grado el menor desagrado por parte del p\u00fablico participe del mercado pol\u00edtico, por ende dentro del sistema pol\u00edtico y su relaci\u00f3n con la sociedad, los medios de comunicaci\u00f3n de masas se han vuelto el nexo m\u00e1s fuerte siendo el principal el medio televisivo y digital. <\/p>\n\n\n\n<p style=\"text-align:justify\">Aunque el poder no se encuentre realmente en ellos es necesario recalcar la gran relevancia que tienen esto sobre el control de la informaci\u00f3n que a posteriori genera poder pol\u00edtico, puesto que el enfoque principal no es la modelaci\u00f3n de la opini\u00f3n p\u00fablica que puedan lograr con el contenido que exponen en sus medios, sino la ausencia o en algunos casos censura de mensaje informativos sobre temas determinados que deber\u00edan ser conocidos por la poblaci\u00f3n para un mejor entendimiento y comprensi\u00f3n del mismo. Es ah\u00ed la cuesti\u00f3n un contenido no existente en los medios no existe en la opini\u00f3n p\u00fablica a pesar de su presencia fragmentada en el pensamiento individual del ciudadano. Por lo que se sintetiza que un mensaje pol\u00edtico necesariamente es medi\u00e1tico.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tanto la comunicaci\u00f3n como la pol\u00edtica est\u00e1n limitadas a ejercerse dentro de un determinado territorio, contexto o cultura para poder lograr un \u00f3ptimo desarrollo para con sus part\u00edcipes, de lo contrario ambos procesos terminar\u00edan siendo obsoletos, partiendo de esta premisa podemos observar la relaci\u00f3n entre la comunicaci\u00f3n y la pol\u00edtica siendo ambas aplicables dentro del [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":6946,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[358,359,33],"tags":[781,635,89],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6849"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=6849"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6849\/revisions"}],"predecessor-version":[{"id":6945,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6849\/revisions\/6945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/6946"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=6849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=6849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=6849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}