{"id":6854,"date":"2021-01-07T00:17:32","date_gmt":"2021-01-07T05:17:32","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=6854"},"modified":"2021-01-07T00:17:35","modified_gmt":"2021-01-07T05:17:35","slug":"las-mujeres-que-aparecen-en-las-nuevas-monedas-de-un-sol","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/las-mujeres-que-aparecen-en-las-nuevas-monedas-de-un-sol\/","title":{"rendered":"Las mujeres que aparecen en las nuevas monedas de un sol"},"content":{"rendered":"\n<p style=\"text-align:justify\">El Banco Central de Reserva del Per\u00fa anunci\u00f3 la nueva serie de monedas del Per\u00fa \u00abLa mujer en el proceso de la independencia del Per\u00fa\u00bb, rinde homenaje a las mujeres que lucharon por la independencia de nuestro pa\u00eds. Ellas tuvieron un rol importante al resguardar y trasladar informaci\u00f3n secreta en ese contexto.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/elcomercio.pe\/resizer\/m1ssTERXuFdZYa1dLS_4wQUf1vU=\/580x330\/smart\/filters:format(jpeg):quality(75)\/cloudfront-us-east-1.images.arcpublishing.com\/elcomercio\/TOYZMK6EVNFCHF2W6CLDA5CJCM.jpg\" alt=\"Las monedas son de curso legal, por lo que pueden ser usadas en cualquier transacci\u00f3n econ\u00f3mica. (Foto: BCR)\" width=\"432\" height=\"245\" \/><figcaption> Las monedas son de curso legal, por lo que pueden ser usadas en cualquier transacci\u00f3n econ\u00f3mica. (Foto: BCR) <br><\/figcaption><\/figure><\/div>\n\n\n\n<p style=\"text-align:justify\">Las tres monedas est\u00e1n protagonizadas por&nbsp;<strong>Mar\u00eda Parado de Bellido<\/strong>,&nbsp;<strong>Br\u00edgida Silva de Ochoa<\/strong>&nbsp;y las&nbsp;<strong>hero\u00ednas Toledo<\/strong>. Todas protagonizaron importantes acciones en el proceso de nuestra emancipaci\u00f3n. En el anverso de las monedas se observa el Escudo de Armas del Per\u00fa rodeado de la leyenda \u201cBANCO CENTRAL DE RESERVA DEL PER\u00da\u201d, el a\u00f1o de acu\u00f1aci\u00f3n y un pol\u00edgono inscrito de ocho lados que forma el filete de la moneda. <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Banco Central de Reserva del Per\u00fa anunci\u00f3 la nueva serie de monedas del Per\u00fa \u00abLa mujer en el proceso de la independencia del Per\u00fa\u00bb, rinde homenaje a las mujeres que lucharon por la independencia de nuestro pa\u00eds. Ellas tuvieron un rol importante al resguardar y trasladar informaci\u00f3n secreta en ese contexto. Las tres monedas [&hellip;]<\/p>\n","protected":false},"author":121,"featured_media":7161,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[34,30,357],"tags":[910,911,296],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6854"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/121"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=6854"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6854\/revisions"}],"predecessor-version":[{"id":7160,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6854\/revisions\/7160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/7161"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=6854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=6854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=6854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}