{"id":6914,"date":"2021-01-06T03:11:05","date_gmt":"2021-01-06T08:11:05","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=6914"},"modified":"2021-01-06T03:11:08","modified_gmt":"2021-01-06T08:11:08","slug":"juego-de-tronos-que-hace-tan-intrigante-a-los-libros","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/juego-de-tronos-que-hace-tan-intrigante-a-los-libros\/","title":{"rendered":"Juego de tronos \u00bfQu\u00e9 hace tan intrigante a los libros?"},"content":{"rendered":"\n<p>Juego de tronos es una saga de\nlibros escrito por el c\u00e9lebre George R. R. Mart\u00edn, que desde su primera\npublicaci\u00f3n en 1996, ha cultivado millones de lectores a trav\u00e9s de todo el\nmundo. La saga cuenta con una adaptaci\u00f3n a la televisi\u00f3n,&nbsp; que agrado tan al p\u00fablico como a la cr\u00edtica\n(al menos en sus primeras temporadas) y que populariz\u00f3 m\u00e1s a los libros.<\/p>\n\n\n\n<p>Pero no estamos aqu\u00ed para hablar\nde la serie, sino de los libros. Escritos de manera coral a partir de distintos\npuntos de vista, nos narra la lucha entre varias familias de la nobleza del\ncontinente imaginario de Poniente por el trono de hierro y que nada los\ndetendr\u00e1 para ganarlo a cualquier precio.<\/p>\n\n\n\n<p>El gran escritor teje las tramas\nde manera inteligente, desembocando en algunos momentos considerados nudos,\ndonde los personajes centrales se encuentran para resolver el conflicto &nbsp;del momento. El estilo de distintos puntos de\nvista hace que formemos v\u00ednculos con la mayor\u00eda de los personajes y los giros\nde trama hacen que nos enganchemos cada vez m\u00e1s con los libros.<\/p>\n\n\n\n<p>A pesar de que la saga sigue inconclusa\n(al menos por ahora), siguen siendo una buena recomendaci\u00f3n de lectura para\nolvidarnos de este contexto pand\u00e9mico, pues sus personajes grises nos mantendr\u00e1n\nal filo de cada libro con sus decisiones. <\/p>\n\n\n\n<p>Imagen extra\u00edda de: https:\/\/fueradeseries.com\/los-pajaritos-de-varys-cu%C3%A1l-es-vuestro-libro-favorito-de-juego-de-tronos-79af4228385d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juego de tronos es una saga de libros escrito por el c\u00e9lebre George R. R. Mart\u00edn, que desde su primera publicaci\u00f3n en 1996, ha cultivado millones de lectores a trav\u00e9s de todo el mundo. La saga cuenta con una adaptaci\u00f3n a la televisi\u00f3n,&nbsp; que agrado tan al p\u00fablico como a la cr\u00edtica (al menos en [&hellip;]<\/p>\n","protected":false},"author":79,"featured_media":6915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6914"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=6914"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6914\/revisions"}],"predecessor-version":[{"id":6916,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/6914\/revisions\/6916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/6915"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=6914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=6914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=6914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}