{"id":7461,"date":"2021-01-08T17:19:34","date_gmt":"2021-01-08T22:19:34","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=7461"},"modified":"2021-01-08T17:22:51","modified_gmt":"2021-01-08T22:22:51","slug":"como-organizar-un-evento-online","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/como-organizar-un-evento-online\/","title":{"rendered":"\u00bfC\u00f3mo organizar un evento online?"},"content":{"rendered":"\n<p style=\"text-align:justify\">Las marcas exitosas son aquellas que pueden adaptarse ante las diferentes circunstancias y estar preparados para vivir \u00fanicamente de forma digital ha salvado a muchos, por lo que organizar un evento online cobra m\u00e1s sentido que nunca.  <\/p>\n\n\n\n<figure class=\"wp-block-image caption-align-right\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/eventos-online.jpg\" alt=\"\" class=\"wp-image-7462\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/eventos-online.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/eventos-online-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Fuente: Sergofi<\/figcaption><\/figure>\n\n\n\n<p style=\"text-align:justify\">Tener a tu lado plataformas para automatizar tus pr\u00e1cticas de marketing online y gestionar a tus clientes potenciales son fundamentales. Es una oportunidad para diversificarse y organizar eventos online. <\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 es un evento online?<\/strong><\/p>\n\n\n\n<p style=\"text-align:justify\">Seg\u00fan <a href=\"https:\/\/es.semrush.com\/user\/148161361\/\" class=\"ek-link\">Emanuel Olivier<\/a>, un evento es un suceso o un acontecimiento planificado con una fecha, hora y lugar definidos y que cumple con diferentes objetivos seg\u00fan cada marca o cada empresa. En el caso de los eventos online, aplica la misma definici\u00f3n, sin embargo, cambia el hecho de que los invitados y los presentadores interact\u00faan a trav\u00e9s de una plataforma digital.<\/p>\n\n\n\n<p style=\"text-align:justify\">Entre los principales beneficios que obtienes al organizar un evento online encontramos:<\/p>\n\n\n\n<p><strong>1.- No hay l\u00edmites geogr\u00e1ficos<\/strong><\/p>\n\n\n\n<p style=\"text-align:justify\">Cuando realizas un evento online, la locaci\u00f3n no forma parte de los temas que tienes que atender. Cualquier persona con un dispositivo digital y acceso a Internet, podr\u00e1 asistir a tu evento online sin mayor complicaci\u00f3n. Lo \u00fanico que podr\u00eda influir es la zona horaria de la transmisi\u00f3n, con respecto a la ubicaci\u00f3n de los asistentes.<\/p>\n\n\n\n<p><strong>2.- Mayor capacidad de invitados<\/strong><\/p>\n\n\n\n<p style=\"text-align:justify\">Al momento de realizar eventos presenciales, muchas veces la capacidad de los espacios f\u00edsicos pueden ser un dolor de cabeza para los organizadores. Si vas a organizar un evento online, tienes m\u00faltiples opciones seg\u00fan la plataforma que escojas para establecer la cantidad de asistentes. Adem\u00e1s, al realizar tu evento online, no tendr\u00e1s que pensar en decoraci\u00f3n, accesibilidad o servicios especiales.<\/p>\n\n\n\n<p><strong>3.- Inmediatez en las interacciones<\/strong><\/p>\n\n\n\n<p style=\"text-align:justify\">En muchos de los eventos presenciales, la din\u00e1mica suele ser escuchar al ponente y luego abrir una ronda de preguntas y respuestas o de debate para poder interactuar, sin embargo, la comunicaci\u00f3n suele ser unilateral. En el caso de los eventos online, los asistentes pueden interactuar entre ellos durante la transmisi\u00f3n y as\u00ed mismo, dejar preguntas y comentarios que pueden ser respondidas de forma inmediata por el organizador, permitiendo as\u00ed, una comunicaci\u00f3n m\u00e1s r\u00e1pida y directa.<\/p>\n\n\n\n<p><strong>4.- Facilidad para transmitir en diferentes idiomas<\/strong><\/p>\n\n\n\n<p style=\"text-align:justify\">Aunque el presentador transmita la informaci\u00f3n en un solo idioma, al hacerlo a trav\u00e9s de plataformas digitales, brinda la opci\u00f3n del uso de subt\u00edtulos. Esta herramienta, te ayudar\u00e1 a llegar de forma efectiva a m\u00e1s cantidad de personas, sin importar el pa\u00eds donde se encuentren ni el idioma que estas hablen.<\/p>\n\n\n\n<p><strong>5.- Reducci\u00f3n de costos de producci\u00f3n<\/strong><\/p>\n\n\n\n<p style=\"text-align:justify\">Sabemos que organizar un evento presencial, requiere mucho trabajo y esfuerzo. Hay que invertir en espacios, decoraci\u00f3n, publicidad, medios, invitaciones, alg\u00fan detalle para los invitados, incluso comidas y bebidas. Todos estos elementos no son necesarios al momento de organizar un evento online. Solo necesitas un dispositivo digital con una buena c\u00e1mara y un buen audio, as\u00ed como un espacio donde el presentador pueda transmitir de forma efectiva su mensaje.<\/p>\n\n\n\n<p><strong>6.- Rentabilidad<\/strong><\/p>\n\n\n\n<p style=\"text-align:justify\">Organizar un evento online, te dejar\u00e1 una mayor cantidad de ingresos al ahorrar todos los gastos de producci\u00f3n y podr\u00e1s ver un mejor retorno de la inversi\u00f3n. Ahora bien, quiz\u00e1s tengas dudas de si tu marca puede organizar eventos online por su categor\u00eda o dependiendo del rubro donde te desenvuelvas.&nbsp;<\/p>\n\n\n\n<p><strong>Plataformas para organizar tu evento online<\/strong><\/p>\n\n\n\n<p style=\"text-align:justify\">La elecci\u00f3n de la plataforma para organizar tu evento debe depender de tus objetivos, la cantidad de asistentes y de tu presupuesto. Aunque muchas ofrezcan opciones gratuitas, usualmente estas tienen limitaciones, en especial relacionadas a la cantidad de asistentes, sin embargo, suelen tener buenas opciones.<\/p>\n\n\n\n<p style=\"text-align:justify\">A continuaci\u00f3n compartiremos contigo, cinco de las plataformas para organizar eventos online m\u00e1s populares.<\/p>\n\n\n\n<ul><li><a href=\"https:\/\/www.eventbrite.es\/\" class=\"ek-link\">Eventbrite<\/a><\/li><li><a href=\"https:\/\/www.gotomeeting.com\/es-es\/webinar\" class=\"ek-link\">Go to webinar<\/a><\/li><li><a href=\"https:\/\/www.eventtia.com\/es\/inicio\" class=\"ek-link\">Eventtia<\/a><\/li><li><a href=\"https:\/\/www.classonlive.com\/\" class=\"ek-link\">Class onlive<\/a><\/li><li><a href=\"https:\/\/www.anymeeting.com\/AccountManager\/Login.aspx\" class=\"ek-link\">Anymeeting<\/a><\/li><\/ul>\n\n\n\n<p>Fuente: <a href=\"https:\/\/es.semrush.com\/blog\/\" class=\"ek-link\">Semrush Blog<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las marcas exitosas son aquellas que pueden adaptarse ante las diferentes circunstancias y estar preparados para vivir \u00fanicamente de forma digital ha salvado a muchos, por lo que organizar un evento online cobra m\u00e1s sentido que nunca. Tener a tu lado plataformas para automatizar tus pr\u00e1cticas de marketing online y gestionar a tus clientes potenciales [&hellip;]<\/p>\n","protected":false},"author":144,"featured_media":7467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[361,360,362,550,363],"tags":[1016,1017,645],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/7461"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/144"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=7461"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/7461\/revisions"}],"predecessor-version":[{"id":7466,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/7461\/revisions\/7466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/7467"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=7461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=7461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=7461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}