{"id":7555,"date":"2021-01-10T23:48:09","date_gmt":"2021-01-11T04:48:09","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=7555"},"modified":"2021-01-10T23:48:12","modified_gmt":"2021-01-11T04:48:12","slug":"colombia-las-velitas-que-nunca-se-extinguen","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/colombia-las-velitas-que-nunca-se-extinguen\/","title":{"rendered":"Colombia: Las velitas que nunca se extinguen"},"content":{"rendered":"\n<p>En Colombia la navidad se inicia mucho antes que\nel 24 de diciembre, en una fecha que para muchos anuncia&nbsp;el momento en que la Virgen Mar\u00eda es elegida para\nllevar en su vientre al hijo de dios, Jes\u00fas. El <a href=\"https:\/\/conexioncapital.co\/por-que-en-colombia-celebramos-el-dia-de-las-velitas\/\">07\nde diciembre<\/a> de cada a\u00f1o los colombianos se re\u00fanen en familia o amigos para\nencender una vela o varias, mientras escuchan canciones populares como&nbsp;Las\ncuatro fiestas&nbsp;e&nbsp;Inmaculada y comen postres t\u00edpicos de la regi\u00f3n como\nbu\u00f1uelos y la natilla.<\/p>\n\n\n\n<p>La celebraci\u00f3n aunque tiene un\ncar\u00e1cter religioso, fue adquiriendo un fin comercial&nbsp;con el tiempo, siendo\nfestejada por creyentes y no creyentes, ese mismo d\u00eda las instituciones,\ntiendas e industrias se suman al festejo encendiendo l\u00e1mparas, faroles y los\ndecorados navide\u00f1os, pues esta fecha tambi\u00e9n marca el inicio de la navidad y de\nlo que para muchos es el mes m\u00e1s feliz del a\u00f1o.<\/p>\n\n\n\n<p>En algunas partes del pa\u00eds,\nsobre todo en&nbsp;Bucaramanga, las familias encienden&nbsp;las velas la noche\ndel 7 y al d\u00eda siguiente izan la bandera de la Virgen Mar\u00eda en las ventanas y\nbalcones de las casas y edificios. En otros lugares, se acostumbra a dejar las\nvelas y faroles prendidos hasta la ma\u00f1ana del 08 de diciembre; organizar fiestas\ny eventos multitudinarios, armar altares para la virgen, e iluminar calles\nenteras de faroles, para lo que se bloquean algunas pistas.&nbsp;<\/p>\n\n\n\n<p>El origen de la festividad se atribuye a una mezcla de dos tradiciones, el <a href=\"https:\/\/www.bbc.com\/mundo\/noticias-55260709\">Januc\u00e1<\/a> por un lado y la Inmaculada Concepci\u00f3n por el otro.\u00a0Januc\u00e1, en hebreo rededicaci\u00f3n, es una celebraci\u00f3n jud\u00eda que conmemora la rebeli\u00f3n de los macabeos que les permiti\u00f3 su independencia del imperio Sel\u00e9ucida. Durante el proceso de rededicaci\u00f3n o purificaci\u00f3n se encendi\u00f3\u00a0una l\u00e1mpara, que seg\u00fan cuenta la tradici\u00f3n se mantuvo prendida durante ocho d\u00edas cuando apenas ten\u00eda combustible para uno, los jud\u00edos consideraron esto un milagro y desde entonces lo celebran\u00a0a partir del 25 de Kislev, el tercer mes del calendario hebreo, que en nuestro calendario equivale a los \u00faltimos\u00a0d\u00edas de noviembre y principios de diciembre.\u00a0 <\/p>\n\n\n\n<p>Estos d\u00edas tristemente tambi\u00e9n coinciden con las fechas en que <a href=\"https:\/\/bogota.gov.co\/mi-ciudad\/gobierno\/distrito-invita-celebrar-en-familia-la-noche-de-velitas\">m\u00e1s casos de incendios o accidentes<\/a> por p\u00f3lvora se suscitan (esto especialmente en Antioqu\u00eda).\u00a0Frente a esto las autoridades del pa\u00eds hacen cada a\u00f1o un llamado a la conciencia y a la responsabilidad de los ciudadanos. Desde el Gobierno se prohibi\u00f3 la producci\u00f3n, venta y compra de p\u00f3lvora o elementos como cohetes, voladores y bengalas. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Colombia la navidad se inicia mucho antes que el 24 de diciembre, en una fecha que para muchos anuncia&nbsp;el momento en que la Virgen Mar\u00eda es elegida para llevar en su vientre al hijo de dios, Jes\u00fas. El 07 de diciembre de cada a\u00f1o los colombianos se re\u00fanen en familia o amigos para encender [&hellip;]<\/p>\n","protected":false},"author":110,"featured_media":7556,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[34,331],"tags":[1032,1033,667],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/7555"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/110"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=7555"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/7555\/revisions"}],"predecessor-version":[{"id":7557,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/7555\/revisions\/7557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/7556"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=7555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=7555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=7555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}