{"id":7639,"date":"2021-01-12T02:16:16","date_gmt":"2021-01-12T07:16:16","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=7639"},"modified":"2021-01-12T02:16:33","modified_gmt":"2021-01-12T07:16:33","slug":"nuevas-alternativas-una-alta-migracion-a-telegram","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/nuevas-alternativas-una-alta-migracion-a-telegram\/","title":{"rendered":"Nuevas alternativas: Una alta migraci\u00f3n a Telegram"},"content":{"rendered":"\n<p><strong>Las nuevas pol\u00edticas de privacidad de whatsapp generaron una alta cifra de migraci\u00f3n a Telegram, tras conocer sus beneficios.<\/strong><\/p>\n\n\n\n<p>Ante un comunicado, a inicios del presente a\u00f1o, por parte de la red social whatsapp miles de internautas decidieron migrar a otras alternativas. Como cada a\u00f1o las <a href=\"https:\/\/www.whatsapp.com\/legal\/updates\/terms-of-service\/?lang=es\" class=\"ek-link\">pol\u00edticas de esta red social<\/a> se actualizan generando as\u00ed grandes pol\u00e9micas, el 2021 no era diferente en una notificaci\u00f3n se comunic\u00f3 que se cambiar\u00e1 sus pol\u00edticas privadas sobre sus usuarios,\u00a0compartiendo la informaci\u00f3n de ellos con Facebook, su empresa matriz, y d\u00e1ndole mayor protagonismo a los comerciantes para publicidades. Las reacciones no se hicieron esperar en redes sociales, tras el comunicado. Algunos internautas comunicaron sobre la existencia de una red social muy parecida a whatsapp e incluso con mucha m\u00e1s privacidad y seguridad:<a href=\"https:\/\/twitter.com\/telegram?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1348266599216795648%7Ctwgr%5E%7Ctwcon%5Es1_&amp;ref_url=https%3A%2F%2Frpp.pe%2Ftecnologia%2Fwhatsapp%2Ftelegram-vs-signal-conoce-las-ventajas-y-diferencias-de-los-servicios-de-mensajeria-alternos-a-whatsapp-facebook-noticia-1314292\" class=\"ek-link\"> Telegram<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/VS.TELEGRAM.jpg\" alt=\"\" class=\"wp-image-7640\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/VS.TELEGRAM.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/VS.TELEGRAM-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<p>Esta compa\u00f1\u00eda rusa, lleva ya un tiempo compitiendo con whatsapp, en estos \u00faltimos d\u00edas se logr\u00f3 ver una alta migraci\u00f3n generada as\u00ed por la nueva pol\u00edtica que se iniciar\u00e1 el pr\u00f3ximo 8 de febrero. Esta red social fue creada en el 2013 con los rusos Nikolai y Pavel Durov, teniendo una amplia acogida debido sus novedosas y grandes ventajas. Pero, <strong>\u00bfcu\u00e1les son estas ventajas?<\/strong><\/p>\n\n\n\n<ol><li>Permite\u00a0enviar archivos de hasta 2 GB de manera libre y sencilla en sus chats.<\/li><li>Los usuarios pueden crear grupos o canales informativos de hasta 200 mil integrantes en comparaci\u00f3n con los 256 participantes que whatsapp permite.<\/li><li>Los mensajes se autodestruyan tras cierto tiempo.<\/li><li>Permite\u00a0conversaciones secretas\u00a0que\u00a0deshabilitan la funci\u00f3n de toma de captura de los mensajes.<\/li><li>Existe la\u00a0autentificaci\u00f3n en 2 pasos,\u00a0iniciando sesi\u00f3n con una contrase\u00f1a y un m\u00e9todo alternativo (como un mensaje de texto).<\/li><li>Se puede acceder desde diferentes y m\u00faltiples dispositivos.<\/li><\/ol>\n\n\n\n<p>Respecto a la privacidad, tema que ha hizo migrar a miles de usuarios, Telegram usa el\u00a0<strong><a href=\"https:\/\/tecnonucleous.com\/2018\/09\/11\/telegram-mtproto-proxy-todo-lo-que-sabemos-sobre-el\/\" class=\"ek-link\">MTProto<\/a>,<\/strong>\u00a0una de las mejores formas de seguridad en el mercado. Adem\u00e1s que las conversaciones se quedan en la nube. Es as\u00ed como Telegram se posiciona en una de las aplicaciones con mayores beneficios y pocos riesgos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las nuevas pol\u00edticas de privacidad de whatsapp generaron una alta cifra de migraci\u00f3n a Telegram, tras conocer sus beneficios. Ante un comunicado, a inicios del presente a\u00f1o, por parte de la red social whatsapp miles de internautas decidieron migrar a otras alternativas. Como cada a\u00f1o las pol\u00edticas de esta red social se actualizan generando as\u00ed [&hellip;]<\/p>\n","protected":false},"author":127,"featured_media":7640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[44,363],"tags":[631,228,1045,993],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/7639"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/127"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=7639"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/7639\/revisions"}],"predecessor-version":[{"id":7641,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/7639\/revisions\/7641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/7640"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=7639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=7639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=7639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}