{"id":7646,"date":"2021-01-12T08:04:57","date_gmt":"2021-01-12T13:04:57","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=7646"},"modified":"2021-01-12T08:04:59","modified_gmt":"2021-01-12T13:04:59","slug":"vacunas-para-combatir-el-covid-19-podran-ser-comercializadas","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/vacunas-para-combatir-el-covid-19-podran-ser-comercializadas\/","title":{"rendered":"Vacunas para combatir el Covid-19 podr\u00e1n ser comercializadas"},"content":{"rendered":"\n<p>El Decreto Legislativo\npublicado en El Peruano el d\u00eda 11 de enero, establece que las vacunas podr\u00e1n ser\ncomercializadas por el sector privado a partir del 2022, as\u00ed mismo permite la\nimportaci\u00f3n de vacunas por laboratorios privados.<\/p>\n\n\n\n<p>Para que los\nlaboratorios privados puedan distribuir las vacunas deber\u00e1n tener un registro\nsanitario condicional, en el cual est\u00e9n autorizados en distribuir, fabricar,\nalmacenar, comercializar y\/o dispensar tales medicamentos. <\/p>\n\n\n\n<p>Se establece que este\nregistro sanitario tendr\u00e1 una vigencia de un a\u00f1o y solo aplicar\u00eda para estudios\ncl\u00ednicos que se encuentren en fase 3 y con resultados preliminares, ello con el\nobjetivo de tratar preliminarmente enfermedades debilitantes o mortales\nestablecidos por la Organizaci\u00f3n Mundial de la Salud. <\/p>\n\n\n\n<p>El plazo para que\nlaboratorios privados puedan obtener tal registro son de 90 d\u00edas h\u00e1biles calendario\na partir de la presentaci\u00f3n de la solicitud, en los cuales se denegar\u00e1 o\naprobar\u00e1 la solicitud presentada. Aquellos laboratorios que obtengan el\nregistro tendr\u00e1n que cumplir ciertas especificaciones de calidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Decreto Legislativo publicado en El Peruano el d\u00eda 11 de enero, establece que las vacunas podr\u00e1n ser comercializadas por el sector privado a partir del 2022, as\u00ed mismo permite la importaci\u00f3n de vacunas por laboratorios privados. Para que los laboratorios privados puedan distribuir las vacunas deber\u00e1n tener un registro sanitario condicional, en el cual [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":7647,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[329,328,482],"tags":[166,1046,215],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/7646"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=7646"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/7646\/revisions"}],"predecessor-version":[{"id":7648,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/7646\/revisions\/7648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/7647"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=7646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=7646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=7646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}