{"id":7842,"date":"2021-01-14T02:09:40","date_gmt":"2021-01-14T07:09:40","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=7842"},"modified":"2021-01-14T02:17:08","modified_gmt":"2021-01-14T07:17:08","slug":"las-representaciones-ideologicas-en-el-cartelismo-nazi","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/las-representaciones-ideologicas-en-el-cartelismo-nazi\/","title":{"rendered":"Las representaciones ideol\u00f3gicas en el cartelismo Nazi"},"content":{"rendered":"\n<p style=\"text-align:justify\">Han pasado unos 88 a\u00f1os desde que iniciar\u00eda el r\u00e9gimen nazi que gobern\u00f3 Alemania de 1933 a 1945 con la llegada al poder del Partido Nacionalsocialista Obrero Alem\u00e1n de Adolf Hitler (NSDAP). Como art\u00edculo de investigaci\u00f3n se describir\u00e1 de forma breve como se fue difundiendo la ideolog\u00eda partiendo del cartelismo.<\/p>\n\n\n\n<p style=\"text-align:justify\">Luego que Alemania pasara por una crisis econ\u00f3mica y social, debido a los sucesos entreguerras; el nacionalismo se encontraba debilitado y el sector obrero y militar se mostrada especialmente deca\u00eddo.  El nazismo lo que trat\u00f3 de hacer es buscar culpables mediante la segregaci\u00f3n y el levantamiento de una moral nacionalista mediante el exaltamiento de los ideales de alem\u00e1n \u00abpuro\u00bb. Esto no se form\u00f3 de un d\u00eda para otro sino que tuvo la influencia de Joseph Goebells; quien tom\u00f3 la posici\u00f3n de jefe de propaganda y ministro en el gobierno nazi. <\/p>\n\n\n\n<p>Mediante el cartel lo que podemos ver de la propaganda es que estuvo segmentada a diferentes tipos de p\u00fablico y estuvo en todos los espacios de convivencia social posible. Esto podr\u00edamos dividirlo en 4 partes seg\u00fan dimensiones de creaci\u00f3n de personajes:<\/p>\n\n\n\n<p style=\"text-align:left\" class=\"has-medium-font-size\"><strong>La representaci\u00f3n juvenil<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/01cb74ccd6ce3e5702fef6ec63b52ece-3.jpg\" alt=\"\" class=\"wp-image-7883\" width=\"291\" height=\"412\" \/><figcaption>Ilustraci\u00f3n 1<\/figcaption><\/figure><\/div>\n\n\n\n<p style=\"text-align:justify\" class=\"has-small-font-size\">Exist\u00eda un papel protag\u00f3nico por parte de los j\u00f3venes en la propaganda nazi. Representados como sin\u00f3nimos de valent\u00eda, masculinidad y nacionalismo se orientaba a los j\u00f3venes en formaci\u00f3n a compartir la ideolog\u00eda nazista, formarse una identidad desde esta e inscribirse al ej\u00e9rcito.<\/p>\n\n\n\n<p style=\"text-align:justify\" class=\"has-small-font-size\">Esto es debido tambi\u00e9n a un mito del cuerpo y la superioridad que como explica montes (2012) en la representaci\u00f3n del cuerpo exist\u00eda una polarizaci\u00f3n de valores ligados a lo racial. Aunque esto se vaya a otro punto la identidad del cuerpo fuerte relacionado al alem\u00e1n blanco es una idea de la que no existe otra posibilidad en la ideolog\u00eda nazista.<\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"text-align:left\" class=\"has-medium-font-size\"><strong>Los estereotipos jud\u00edos<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/2d53c570-2e68-4574-baf0-77cd886a7b4f.png\" alt=\"\" class=\"wp-image-7889\" width=\"258\" height=\"391\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/2d53c570-2e68-4574-baf0-77cd886a7b4f.png 529w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/2d53c570-2e68-4574-baf0-77cd886a7b4f-198x300.png 198w\" sizes=\"(max-width: 258px) 100vw, 258px\" \/><figcaption>Ilustraci\u00f3n 2<\/figcaption><\/figure><\/div>\n\n\n\n<p style=\"text-align:justify\" class=\"has-small-font-size\">Tambi\u00e9n exist\u00eda el uso de ciertos estereotipos en torno a los jud\u00edos los cuales eran reducidos a un car\u00e1cter de ego\u00edsmo e invasi\u00f3n transgresora. <\/p>\n\n\n\n<p style=\"text-align:justify\" class=\"has-small-font-size\">Sea racional o no la conexi\u00f3n se culpaba a los jud\u00edos de un empobrecimiento para el resto de los alemanes, los cuales obviamente sufr\u00edan en su adquisici\u00f3n econ\u00f3mica por la crisis. Montes (2012) menciona que mientras la ideolog\u00eda nazi exalta la juventud al jud\u00edo lo identifica con la vejez y la diferencia, se le caricaturiza en un cuerpo extra\u00f1o y como un agente social excluido del proyecto nazi. <\/p>\n\n\n\n<p class=\"has-small-font-size\">Es una ant\u00edtesis de representaci\u00f3n formulada.<\/p>\n\n\n\n<div style=\"height:41px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:17px;text-align:left\"><strong>La representaci\u00f3n femenina<\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img decoding=\"async\" loading=\"lazy\" width=\"202\" height=\"300\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/Cartel-imperial-War-museum-L\u00f3ndres-202x300.png\" alt=\"\" class=\"wp-image-7893\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/Cartel-imperial-War-museum-L\u00f3ndres-202x300.png 202w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/Cartel-imperial-War-museum-L\u00f3ndres.png 563w\" sizes=\"(max-width: 202px) 100vw, 202px\" \/><figcaption>Ilustraci\u00f3n 3<\/figcaption><\/figure><\/div>\n\n\n\n<p style=\"text-align:justify\" class=\"has-small-font-size\">De parte de la mujer, esta estuvo limitada a las actividades del hogar anteriormente; por lo que en el nazismo se le hace una relativa mejora de condiciones o de reconocimiento social al darle visualizaci\u00f3n y trabajo de repartici\u00f3n de alimentos o pedidos de apoyo dentro del partido. <\/p>\n\n\n\n<p style=\"text-align:justify\" class=\"has-small-font-size\">En el cartel expuesto no se muestra m\u00e1s que una forma de intentar simpatizar al p\u00fablico que se fije en la mujer que pide apoyar el r\u00e9gimen y donaci\u00f3n para refugios<\/p>\n\n\n\n<p style=\"text-align:justify\" class=\"has-small-font-size\">Sin embargo, estas peque\u00f1as evidencias demuestran una representaci\u00f3n continua a la que anteriormente no se le mostraba importancia.<\/p>\n\n\n\n<div style=\"height:22px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:18px;text-align:left\"><strong>La \u00abfamilia\u00bb alemana<\/strong><\/p>\n\n\n\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/winterhilfswerk-ein-volk-hilft-sich-selbst-209x300.jpg\" alt=\"\" class=\"wp-image-7894\" width=\"216\" height=\"311\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/winterhilfswerk-ein-volk-hilft-sich-selbst-209x300.jpg 209w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/winterhilfswerk-ein-volk-hilft-sich-selbst.jpg 450w\" sizes=\"(max-width: 216px) 100vw, 216px\" \/><figcaption>Ilustraci\u00f3n 4<br><\/figcaption><\/figure><\/div>\n\n\n\n<p style=\"text-align:justify\" class=\"has-small-font-size\">Para llegar a la extensi\u00f3n tanto de j\u00f3venes estudiantes, militares y obreros se representaba a la familia \u201cpura\u201d. <\/p>\n\n\n\n<p style=\"text-align:justify\" class=\"has-small-font-size\">Por lo general acompa\u00f1ados por un miembro de vestimenta militar o protegidos por el nazismo, aunque de forma m\u00e1s breve podr\u00eda decirse que la familia aria ya representa parte de la ideolog\u00eda.<\/p>\n\n\n\n<p style=\"text-align:justify\" class=\"has-small-font-size\">Esto pod\u00eda verse en el caso del Reichsadler o \u00e1guila imperial y la misma bandera nazi. <\/p>\n\n\n\n<div style=\"height:82px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul><li><strong>Referencias:<\/strong><\/li><\/ul>\n\n\n\n<p style=\"font-size:11px\">Montes, P. (2012). CUERPOS REPRESENTADOS, CUERPOS DOMINADOS. PODER Y REPRESENTACI\u00d3N EN LOS CARTELES DE PROPAGANDA NAZI Th\u00e9mata. Revista de Filosof\u00eda (46), 707-716. Recuperado de <a href=\"https:\/\/revistascientificas.us.es\/index.php\/themata\/article\/view\/444\" class=\"ek-link\">https:\/\/revistascientificas.us.es\/index.php\/themata\/article\/view\/444<\/a> <\/p>\n\n\n\n<p style=\"font-size:11px;text-align:justify\">Ilustraci\u00f3n 1: <a href=\"https:\/\/i.pinimg.com\/736x\/01\/cb\/74\/01cb74ccd6ce3e5702fef6ec63b52ece.jpg\" class=\"ek-link\">Joven alem\u00e1n en uniforme, lleva un hacha en la mano y est\u00e1 listo para actuar.<\/a><\/p>\n\n\n\n<p style=\"font-size:11px;text-align:justify\">Ilustraci\u00f3n 2: <a href=\"http:\/\/1.bp.blogspot.com\/--OFn0zYsxYY\/VUnghL1JMcI\/AAAAAAAACgU\/TKNtuNnZmXI\/s1600\/Cartel%2Bimperial%2C%2BWar%2Bmuseum%2C%2BL%C3%B3ndres.png\" class=\"ek-link\">\u201cconstruye albergues y hogares juveniles\u201d<\/a>. <\/p>\n\n\n\n<p style=\"font-size:11px\">Ilustraci\u00f3n 3:  <a href=\"https:\/\/userscontent2.emaze.com\/images\/c7156634-ba86-460e-96b7-4f0ec26af1b3\/2d53c570-2e68-4574-baf0-77cd886a7b4f.png\" class=\"ek-link\">Representaci\u00f3n jud\u00eda en la Alemania nazi, enemigo de los obreros.<\/a><\/p>\n\n\n\n<p style=\"font-size:11px;text-align:justify\">Ilustraci\u00f3n 4: <a href=\"https:\/\/diezmasuno.files.wordpress.com\/2015\/01\/winterhilfswerk-ein-volk-hilft-sich-selbst.jpg\" class=\"ek-link\">Familia alemana aria, los hombres se muestran en postura de vigilancia. <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Han pasado unos 88 a\u00f1os desde que iniciar\u00eda el r\u00e9gimen nazi que gobern\u00f3 Alemania de 1933 a 1945 con la llegada al poder del Partido Nacionalsocialista Obrero Alem\u00e1n de Adolf Hitler (NSDAP). Como art\u00edculo de investigaci\u00f3n se describir\u00e1 de forma breve como se fue difundiendo la ideolog\u00eda partiendo del cartelismo. Luego que Alemania pasara por [&hellip;]<\/p>\n","protected":false},"author":115,"featured_media":7862,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[39],"tags":[1078,344],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/7842"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/115"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=7842"}],"version-history":[{"count":21,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/7842\/revisions"}],"predecessor-version":[{"id":7923,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/7842\/revisions\/7923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/7862"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=7842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=7842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=7842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}