{"id":8008,"date":"2021-01-14T12:30:34","date_gmt":"2021-01-14T17:30:34","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=8008"},"modified":"2021-01-14T12:31:01","modified_gmt":"2021-01-14T17:31:01","slug":"terapia-fotografica-su-poder-como-labor-social","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/terapia-fotografica-su-poder-como-labor-social\/","title":{"rendered":"Terapia Fotogr\u00e1fica: Su poder como labor social"},"content":{"rendered":"\n<p>El pasado domingo 20 de diciembre, la comunidad de fot\u00f3grafos <strong>Terapia Fotogr\u00e1fica<\/strong> convirti\u00f3 las afueras del <strong>Hospital V\u00edctor Larco Herrera<\/strong> en una <strong>galer\u00eda art\u00edstica<\/strong> a disposici\u00f3n de todo aquel que quiera disfrutar de estas muestras sin ning\u00fan tipo de restricci\u00f3n o requisito. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/foto2.jpg\" alt=\"\" class=\"wp-image-8036\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/foto2.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/foto2-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Terapia Fotogr\u00e1fica (Imagen: El Comercio).<\/figcaption><\/figure>\n\n\n\n<p>Las  formas de mirar y dar a conocer la <strong>creatividad<\/strong> por medio de  procesos art\u00edsticos y producciones colectivas que favorezcan la b\u00fasqueda, el acceso y el di\u00e1logo, con una intenci\u00f3n hacia la <strong>transformaci\u00f3n<\/strong>, <a href=\"https:\/\/issuu.com\/editorialgrupo5\/docs\/arte__intervencion_y_accion_social._la_creatividad\/18\" class=\"ek-link\">seg\u00fan Olaechea y Engeli<\/a>, manifiesta su poder como parte de la sociedad. La fotograf\u00eda es esa muestra art\u00edstica que tiene gran poder sobre la sociedad, es capaz de construir puentes entre las personas por la conexi\u00f3n que esta transmite. <\/p>\n\n\n\n<p><a href=\"https:\/\/www.terapiafotografica.org\/\" class=\"ek-link\">Terapia Fotogr\u00e1fica<\/a> reconoce el poder de esta, la comunidad naci\u00f3 en plena pandemia y como una alternativa para los estudiantes de fotograf\u00eda que dejaron sus estudios por consecuencias sobre el <a href=\"https:\/\/www.gob.pe\/coronavirus\" class=\"ek-link\">COVID-19<\/a> . Por eso, su misi\u00f3n principal es brindar una educaci\u00f3n visual a todos los latinoamericanos. Reflejando esta idea elaboraron este proyecto llamado <strong>\u00abMuros de la Bondad\u00bb<\/strong> que tiene como prop\u00f3sito generar un espacio de dialogo entre los espectadores. Se trata de 32 fotograf\u00edas que ocupan las fachadas del Hospital V\u00edctor Larco Herrera que convierte el espacio en una de las galer\u00edas m\u00e1s grandes del pa\u00eds. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"668\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/foto.jpg\" alt=\"\" class=\"wp-image-8037\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/foto.jpg 668w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/01\/foto-300x168.jpg 300w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/><figcaption> Terapia Fotogr\u00e1fica (Imagen: El Comercio). <\/figcaption><\/figure>\n\n\n\n<p><strong>Judy Weiser<\/strong>, directora del <a href=\"https:\/\/phototherapy-centre.com\/spanish\/\" class=\"ek-link\">Photo Therapy Centre de Vancouver<\/a>, manifest\u00f3 para <a href=\"https:\/\/psicoguias.com\/fototerapia-2\/\" class=\"ek-link\">Psicogu\u00edas<\/a> que las fotograf\u00edas, a pesar de no tratarse de un autorretrato, proporcionan y son capaces de  acercarte a tu vida interior a trav\u00e9s de una evocaci\u00f3n que se hace a la mente y el coraz\u00f3n. La fototerapia es una herramienta interesante que permite el autodescubrimiento y que genera espacios de interacci\u00f3n con otros mejorando el desarrollo social. <\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/elcomercio.pe\/respuestas\/terapia-fotografica-anticovid-19-la-exposicion-que-convertira-la-fachada-del-larco-herrera-en-galeria-de-arte-fotos-noticia\/?ref=ecr\" class=\"ek-link\">El Comercio<\/a>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado domingo 20 de diciembre, la comunidad de fot\u00f3grafos Terapia Fotogr\u00e1fica convirti\u00f3 las afueras del Hospital V\u00edctor Larco Herrera en una galer\u00eda art\u00edstica a disposici\u00f3n de todo aquel que quiera disfrutar de estas muestras sin ning\u00fan tipo de restricci\u00f3n o requisito. Las formas de mirar y dar a conocer la creatividad por medio de [&hellip;]<\/p>\n","protected":false},"author":120,"featured_media":8035,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[46,34,320,329],"tags":[67,221,1112,1111],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/8008"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/120"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=8008"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/8008\/revisions"}],"predecessor-version":[{"id":8038,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/8008\/revisions\/8038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/8035"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=8008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=8008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=8008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}