{"id":8569,"date":"2021-01-21T22:43:32","date_gmt":"2021-01-22T03:43:32","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=8569"},"modified":"2021-01-22T11:22:48","modified_gmt":"2021-01-22T16:22:48","slug":"el-coronavirus-lo-hizo-de-nuevo-la-literatura-huanuquena-esta-de-luto-tras-la-perdida-del-escritor-andres-cloud","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/el-coronavirus-lo-hizo-de-nuevo-la-literatura-huanuquena-esta-de-luto-tras-la-perdida-del-escritor-andres-cloud\/","title":{"rendered":"El coronavirus lo hizo de nuevo: La literatura huanuque\u00f1a est\u00e1 de luto tras la p\u00e9rdida del escritor Andr\u00e9s Cloud"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote\"><p><em>\u201cNo tengo palabras para expresar este inmenso dolor que siento por la partida de mi maestro y amigo, Andr\u00e9s Cloud. Gracias por todo, hasta siempre. Adi\u00f3s\u201d<\/em>. <\/p><cite>Expres\u00f3 el escritor y poeta Andr\u00e9s Jara Maylle en sus redes sociales, un amigo cercano de Cloud <\/cite><\/blockquote>\n\n\n\n<p>Durante la fr\u00eda madrugada del 14 de enero del nuevo a\u00f1o, a los ochenta a\u00f1os exactos y ganador del premio Cuento de las 2000 palabras (Caretas, 2003), dej\u00f3 de existir tras una larga batalla contra el covid-19, batalla que para infortunio de la literatura peruana no logr\u00f3 ganar. &nbsp;El escritor falleci\u00f3 en su ciudad natal luego de haber sido hospitalizado durante varios d\u00edas, pese a haber sido conectado a un respirador artificial.<\/p>\n\n\n\n<p>Pero, \u00bfQui\u00e9n fue Andr\u00e9s Cloud Cortez? Ahondemos un poco en su casi desconocida historia, Cloud en <a href=\"https:\/\/es.wikipedia.org\/wiki\/Hu%C3%A1nuco\" class=\"ek-link\">Hu\u00e1nuco <\/a>en el a\u00f1o 1941, creciendo en el campo hasta su juventud para despu\u00e9s mudarse a Lima tras haber ingresado a la decana de Am\u00e9rica: la Universidad Nacional Mayor de San Marcos (<a href=\"https:\/\/www.unmsm.edu.pe\/\" class=\"ek-link\">UNMSM<\/a>), en donde estudi\u00f3 educaci\u00f3n. Luego de eso regres\u00f3 a su pueblo para ejercer catedra en la Universidad Hermilio Valdiz\u00e1n.<\/p>\n\n\n\n<p> En 1999 recibi\u00f3 la Medalla del Arte y la Cultura en el \u00e1rea de Literatura del Instituto Nacional de Cultura y en 1983 funda la Agrupaci\u00f3n Cultural \u201cConvergencia\u201d junto a Mario Malpartida, Samuel Cardich y Ra\u00fal Vergara. En su bibliograf\u00eda figuran m\u00e1s de veinte libros, entre sus obras se halla Convergencia: 12 cuentos (1984). Tres en raya (1985), volumen que re\u00fane textos de Mario Malpartida, Samuel C\u00e1rdich; Cr\u00f3nicas de ayer (1987). Sus libros de cuentos son Usted comadre debe acordarse (1987), Don Juli\u00e1n de los gentiles (1988), Cielo de Congona (1990), Bajo la sombra del limonero (1998) y En la vida hay distancias (1999). Entre sus novelas, se cuenta Los \u00faltimos d\u00edas de pap\u00e1 Ata (1999), \u00a1Ay, Carmela! (2003) y El gran desaf\u00edo (2005). <\/p>\n\n\n\n<p>Entre sus\npremios m\u00e1s reconocidos se encuentran el ya mencionado 2000 palabras, el cual\ngan\u00f3 con el cuento \u00a1Eso! (2003), el premio Francisco Izquierdo R\u00edos que le fue\nentregado por la Asociaci\u00f3n Nacional de Escritores y Artistas (ANEA), gan\u00f3\ndistinciones en concursos de cuentos como el Jos\u00e9 Mar\u00eda Arguedas (1977) y fue\nfinalista en las Bienales del Cuento Premio COP\u00c9. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cNo tengo palabras para expresar este inmenso dolor que siento por la partida de mi maestro y amigo, Andr\u00e9s Cloud. Gracias por todo, hasta siempre. Adi\u00f3s\u201d. Expres\u00f3 el escritor y poeta Andr\u00e9s Jara Maylle en sus redes sociales, un amigo cercano de Cloud Durante la fr\u00eda madrugada del 14 de enero del nuevo a\u00f1o, a [&hellip;]<\/p>\n","protected":false},"author":147,"featured_media":8571,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[34,43,356,329],"tags":[],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/8569"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/147"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=8569"}],"version-history":[{"count":2,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/8569\/revisions"}],"predecessor-version":[{"id":8593,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/8569\/revisions\/8593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/8571"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=8569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=8569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=8569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}