{"id":8687,"date":"2021-02-09T18:32:24","date_gmt":"2021-02-09T23:32:24","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=8687"},"modified":"2021-02-09T18:32:27","modified_gmt":"2021-02-09T23:32:27","slug":"tribunal-constitucional-declara-fundada-demanda-de-inconstitucionalidad-contra-ley-que-permite-el-retiro-facultativo-de-la-onp","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/tribunal-constitucional-declara-fundada-demanda-de-inconstitucionalidad-contra-ley-que-permite-el-retiro-facultativo-de-la-onp\/","title":{"rendered":"Tribunal Constitucional declara fundada demanda de inconstitucionalidad contra Ley que permite el retiro facultativo de la ONP"},"content":{"rendered":"\n<p style=\"text-align:left\"><strong>La ley 31083<\/strong>, Ley que establece un r\u00e9gimen especial facultativo de devoluci\u00f3n de los aportes para los aportantes activos e inactivos bajo el Decreto Ley 19990 administrados por la Oficina de Normalizaci\u00f3n Previsional (ONP), que fuera aprobada por el Congreso de la Rep\u00fablica en agosto del 2020, finalmente <strong>fue denegada por el Tribunal Constitucional, que declar\u00f3 fundada la demanda de inconstitucionalidad presentada por el Poder Ejecutivo.<\/strong><\/p>\n\n\n\n<p>El pleno del Tribunal Constitucional emiti\u00f3 su sentencia en el <a href=\"https:\/\/img.lpderecho.pe\/wp-content\/uploads\/2021\/02\/STC-00016-2020-AI-LP.pdf\" class=\"ek-link\">EXPEDIENTE 00016-2020-PI<\/a>, en \u00e9l se lee que los magistrados del \u00f3rgano supremo de interpretaci\u00f3n de la Carta Magna, dirimieron de forma un\u00e1nime a favor de declarar fundada la demanda, y por ende la inconstitucionalidad de la misma .<\/p>\n\n\n\n<p>En la evaluaci\u00f3n de la demanda se desestim\u00f3 el vicio de inconstitucionalidad formal alegado, consider\u00e1ndolo infundado al no haberse contravenido el procedimiento legislativo constitucional en la expedici\u00f3n de la Ley 31083, en tanto, lo relacionado a la naturaleza jur\u00eddica tales como <strong>la intangibilidad de los fondos y las reservas de la seguridad social como garant\u00eda institucional del derecho fundamental a la pensi\u00f3n; la exigencia de sostenibilidad financiera en las modificaciones a los reg\u00edmenes pensionarios vigentes; la administraci\u00f3n de la hacienda p\u00fablica como competencia del Poder Ejecutivo y la prohibici\u00f3n de iniciativa de gasto p\u00fablico que alcanza al Congreso de la Rep\u00fablica; y, el principio de equilibrio y estabilidad presupuestaria<\/strong>, fueron aspectos que primaron en la decisi\u00f3n para declarar fundada la demanda.<\/p>\n\n\n\n<p>Ante esta situaci\u00f3n, <strong>Marianella Ledesma, presidenta del TC,<\/strong> no dej\u00f3 de reconocer el caso, como <strong>paradigm\u00e1tico<\/strong> ya que el mismo ha evidenciado el hist\u00f3rico abandono que sufren millones de peruanos por parte del Estado al no contar con acceso a pensiones dignas. Sin embargo, cuestion\u00f3 que bajo argumentos inconstitucionales el <strong>Poder Legislativo haya generado expectativas imposibles de cumplir<\/strong>.<\/p>\n\n\n\n<p>\u201c<em>Estas acciones u omisiones del Estado nos deben llamar a la reflexi\u00f3n sobre si estamos<\/em> <em>comprendiendo realmente el rol que le corresponde a \u00e9ste, o en un sentido m\u00e1s amplio,<\/em> <em>a reflexionar sobre si tenemos la capacidad de comprender la realidad del sufrimiento<\/em> <em>humano que padecen nuestros ciudadanos o ciudadanas de mayor edad<\/em>\u201d.\u00a0 <\/p>\n\n\n\n<p>Finalmente, con esta decisi\u00f3n <strong>queda expulsada del ordenamiento jur\u00eddico la Ley 31083<\/strong>, norma que permit\u00eda el retiro facultativo de fondos hasta por una UIT a los aportantes activos e inactivos de la ONP.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ley 31083, Ley que establece un r\u00e9gimen especial facultativo de devoluci\u00f3n de los aportes para los aportantes activos e inactivos bajo el Decreto Ley 19990 administrados por la Oficina de Normalizaci\u00f3n Previsional (ONP), que fuera aprobada por el Congreso de la Rep\u00fablica en agosto del 2020, finalmente fue denegada por el Tribunal Constitucional, que [&hellip;]<\/p>\n","protected":false},"author":142,"featured_media":8688,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[190,330,329,33,328],"tags":[73,497,1200,1198,1197,1199],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/8687"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/142"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=8687"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/8687\/revisions"}],"predecessor-version":[{"id":8689,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/8687\/revisions\/8689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/8688"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=8687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=8687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=8687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}