{"id":8826,"date":"2021-06-21T11:16:02","date_gmt":"2021-06-21T16:16:02","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=8826"},"modified":"2021-08-12T22:33:14","modified_gmt":"2021-08-13T03:33:14","slug":"la-vacuna-finalmente-llego","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/la-vacuna-finalmente-llego\/","title":{"rendered":"La vacuna finalmente lleg\u00f3"},"content":{"rendered":"\n<p><strong>Ahora ella es parte de las personas vacunadas en el pa\u00eds m\u00e1s golpeado por el coronavirus<\/strong>.<\/p>\n\n\n\n<p>Cuando Raquel Cort\u00e9z despert\u00f3 aquel mes de\njunio, en el 2021, 5 millones de dosis contra el coronavirus se hab\u00edan aplicado\nen el Per\u00fa. Era s\u00e1bado y ella, por fin, recibir\u00eda la primera dosis de la\nvacuna. No recuerda con qu\u00e9 pie despert\u00f3, pero recuerda el caf\u00e9 que prepar\u00f3\nr\u00e1pidamente y el pan con jamonada que disfrut\u00f3 con parsimonia. <\/p>\n\n\n\n<p>Hizo su d\u00eda con normalidad, aunque no pod\u00eda\ncontener los nervios, o la emoci\u00f3n. Luego del desayuno, barri\u00f3 su peque\u00f1a sala\ny observ\u00f3 la vieja mesa que se ubicaba en el centro, la hab\u00eda comprado con su\nmam\u00e1 y nunca pens\u00f3 en cambiarla, a pesar de que resulta necesaria. Desde que su\nmam\u00e1 muri\u00f3, hace 15 a\u00f1os, Raquel vive sola. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"680\" height=\"374\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-05-09-at-11.45.51.jpg\" alt=\"\" class=\"wp-image-10300\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-05-09-at-11.45.51.jpg 680w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-05-09-at-11.45.51-300x165.jpg 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><figcaption>Fuente: Adrian Puga<\/figcaption><\/figure>\n\n\n\n<p>Llega el mediod\u00eda y sabe que es hora de llamar\na Eroldo, su sobrino, para que la acompa\u00f1e al Estadio Municipal de Santa Anita.\nLo llama con cierto temor, siente que debe ir sola, que no debe molestarlo.\nLlama. Est\u00e1 lista. Espera. Eroldo llega. Parten. Ambos, antes de su llegada,\nresoplan. Las mascarillas, prenda diaria, vibraban junto a sus poseedores.<\/p>\n\n\n\n<p>Eroldo estaciona el carro, un Toyota Corolla\ndel 2002, en el aparcamiento junto al estadio. Hablan de hechos cotidianos\nmientras esperan. \u00bfQue Alex fue a visitarte?\u00bf C\u00f3mo est\u00e1 Richard?\u00bfJhon ya empez\u00f3\na trabajar?.&nbsp;&nbsp; <\/p>\n\n\n\n<p>Momentos despu\u00e9s. la enfermera se acerc\u00f3 al\nveh\u00edculo y les explic\u00f3 el procedimiento a seguir, e inmediatamente introdujo la\njeringa en el peque\u00f1o frasco de cristal, limpia el brazo y sin mayores\naspavientos introduce la jeringa. A Raquel le cambia la cara, de una actitud\nincr\u00e9dula empieza a sonre\u00edr. Siente que puede respirar, que la muerte no est\u00e1\ntan cerca.<\/p>\n\n\n\n<p>\u201cEn ese momento sent\u00ed alivio, sent\u00eda que por fin podr\u00eda estar un poco m\u00e1s tranquila, con menos miedo\u201d dice La raquelucha, como la llaman sus familiares m\u00e1s cercanos. Ahora ella es parte de las personas vacunadas en el <strong>pa\u00eds m\u00e1s golpeado por el coronavirus<\/strong>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ahora ella es parte de las personas vacunadas en el pa\u00eds m\u00e1s golpeado por el coronavirus. Cuando Raquel Cort\u00e9z despert\u00f3 aquel mes de junio, en el 2021, 5 millones de dosis contra el coronavirus se hab\u00edan aplicado en el Per\u00fa. Era s\u00e1bado y ella, por fin, recibir\u00eda la primera dosis de la vacuna. No recuerda [&hellip;]<\/p>\n","protected":false},"author":165,"featured_media":9410,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[482],"tags":[54,286,215],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/8826"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/165"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=8826"}],"version-history":[{"count":5,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/8826\/revisions"}],"predecessor-version":[{"id":10301,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/8826\/revisions\/10301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/9410"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=8826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=8826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=8826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}