{"id":8838,"date":"2021-06-24T10:39:15","date_gmt":"2021-06-24T15:39:15","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=8838"},"modified":"2021-06-25T09:05:30","modified_gmt":"2021-06-25T14:05:30","slug":"un-momento-de-unidad-y-jolgorio-en-la-ciudad","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/un-momento-de-unidad-y-jolgorio-en-la-ciudad\/","title":{"rendered":"Un momento de unidad y jolgorio en la ciudad"},"content":{"rendered":"\n<p>Aquel 5 de junio, un d\u00eda antes de las votaciones para elegir al pr\u00f3ximo presidente del Per\u00fa, fui testigo del efervescente esp\u00edritu colectivo que irradiaba el cierre de campa\u00f1a de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Pedro_Castillo\" class=\"ek-link\">Pedro Castillo Terrones<\/a>, rondero chotano y profesor sindicalista candidato a la presidencia de la Rep\u00fablica por el periodo 2021-2026. <strong>En la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Plaza_Dos_de_Mayo\" class=\"ek-link\">hist\u00f3rica plaza Dos de Mayo<\/a>, el lado m\u00e1s pluricultural del Cercado de Lima, el ambiente era de unidad y jolgorio pese a la creciente polarizaci\u00f3n pol\u00edtica del pa\u00eds<\/strong>. <\/p>\n\n\n\n<p>Eran casi las ocho de la noche cuando\napresur\u00e9 el paso hacia la plaza. Iba por la avenida Alfonso Ugarte y en la\nmedida en que me acercaba, las personas se sumaban con pancartas en mano desde\nlas calles aleda\u00f1as y arreciaban cada vez m\u00e1s las bocinas, los bombos y el\nclamor popular. A lo lejos, las banderas rojiblancas flameaban bajo el denso\ncielo negro y la bruma invernal. Cerca de la plaza entregaban volantes,\nrevistas, semanarios que operaban como \u00f3rganos de expresi\u00f3n de diferentes\ncolectivos y organizaciones culturales que simpatizaban con la figura de\nCastillo. Era una noche prometedora. <\/p>\n\n\n\n<p>Al llegar todos miraban fijamente hacia\nuno de los balcones de las t\u00edpicas casonas coloniales de la plaza. Ah\u00ed fue\ndonde, minutos despu\u00e9s, apareci\u00f3 Pedro Castillo para cobijar la velada y propiciar\nun surco de esperanza hasta al m\u00e1s desentendido en pol\u00edtica: \u201cEste domingo\nvamos a escribir la nueva historia del Per\u00fa con el l\u00e1piz de la cultura y la\ndignidad\u201d. Redondo. Notable. Una frase tan s\u00f3lida, inteligente y edificante\ncomo el l\u00e1piz mismo; lo que se le reclam\u00f3 en los debates televisivos, aqu\u00ed lo\ndemostr\u00f3 con creces.<\/p>\n\n\n\n<p>Minutos despu\u00e9s, ese mismo l\u00e1piz, que es emblema y estampa del partido pol\u00edtico <a href=\"https:\/\/perulibre.pe\/\" class=\"ek-link\"><strong>Per\u00fa Libre<\/strong><\/a><strong>,<\/strong> se paseaba encima del mar de gente. \u201cArriba el l\u00e1piz\u201d, se oy\u00f3 fuerte, cuando al instante son\u00f3 \u201cQu\u00e9 linda flor\u201d, memorable huayno cajamarquino, y los zapateos (y las infaltables cervezas) se hicieron sentir. Ese l\u00e1piz no estaba hecho de madera, sino de gruesos fierros de construcci\u00f3n, fueron tres o cuatro minutos en los que me pas\u00e9 sosteni\u00e9ndolo, riendo por las ocurrencias de qui\u00e9nes se animaban a formar la fila para cargarlo. Por un momento nos detuvimos, nadie defin\u00eda con claridad el norte del l\u00e1piz, unos lo mov\u00edan hacia atr\u00e1s, otros hacia adelante, pero este divisionismo se resolvi\u00f3 r\u00e1pidamente en plena algarab\u00eda, con risas, huayno y un poco de fuerza brusca para que el movimiento del l\u00e1piz no se detenga y siga su camino.&nbsp; <\/p>\n\n\n\n<p>Durante esta peque\u00f1a peripecia pol\u00edtica\nexperiment\u00e9 un sentido de pertenencia, me sent\u00ed cohesionado en un ideal, aglomerado\ny feliz en torno a la multitud de simpatizantes, pocas cosas hay tan poderosas\nque arengar, cegado tal vez por una luz interna, y expresar la esperanza que\nuno como votante y ciudadano genuinamente deposita, al menos as\u00ed el firmamento\nno luce tan mal. Esta fiesta fue, sin duda, uno de los pocos y verdaderos\nencuentros con nuestra pluralidad que se experiment\u00f3 en la campa\u00f1a presidencial\n2021, un encuentro con nosotros mismos, un acto de fe hacia el entendimiento\ngeneralizado por encima de la incertidumbre de la crisis multinivel que hoy\nsigue ganando terreno. Vibras, tensiones pre-bicentenario. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aquel 5 de junio, un d\u00eda antes de las votaciones para elegir al pr\u00f3ximo presidente del Per\u00fa, fui testigo del efervescente esp\u00edritu colectivo que irradiaba el cierre de campa\u00f1a de Pedro Castillo Terrones, rondero chotano y profesor sindicalista candidato a la presidencia de la Rep\u00fablica por el periodo 2021-2026. En la hist\u00f3rica plaza Dos de [&hellip;]<\/p>\n","protected":false},"author":178,"featured_media":8839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[316,334,329],"tags":[1225,963,91,1226,1227],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/8838"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/178"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=8838"}],"version-history":[{"count":3,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/8838\/revisions"}],"predecessor-version":[{"id":8846,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/8838\/revisions\/8846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/8839"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=8838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=8838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=8838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}