{"id":9072,"date":"2021-06-29T14:31:20","date_gmt":"2021-06-29T19:31:20","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=9072"},"modified":"2021-07-08T10:29:20","modified_gmt":"2021-07-08T15:29:20","slug":"caminar-por-seis-planetas-sin-dejar-tierra-alguien-lo-hizo-posible-en-las-calles-de-lima","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/caminar-por-seis-planetas-sin-dejar-tierra-alguien-lo-hizo-posible-en-las-calles-de-lima\/","title":{"rendered":"\u00bfCaminar por seis planetas sin dejar Tierra? Alguien lo hizo posible en las calles de Lima"},"content":{"rendered":"\n<p>Empiezas por Marte, y si recorres tres\ncuadras de frente y doblas a la derecha en la perpendicular, has llegado a\nUrano. Treinta pasos m\u00e1s y un giro a la izquierda, est\u00e1s en J\u00fapiter \u2014una calle\ntan p\u00e1rvula que contradice las dimensiones del planeta m\u00e1s grande del sistema\nsolar\u2014, cuyo final es la tercera cuadra del\njir\u00f3n Saturno, que colinda con Neptuno, Neptuno con el jir\u00f3n Venus, Venus con\nMercurio, y Mercurio con Plut\u00f3n. \u00bfA qui\u00e9n se le ocurri\u00f3 utilizar esos nombres? <strong>\u00bfQui\u00e9n\no qui\u00e9nes son los nomencladores de las calles?<\/strong><\/p>\n\n\n\n<p>Las c\u00f3smicas calles de\nla urbanizaci\u00f3n La Luz en el Cercado de Lima abrieron la interrogante acerca de\nlos art\u00edfices de las asignaciones. Encontrarlos por nombre y apellido quiz\u00e1s\ntome un tiempo, pero iniciar el rastreo implica calzar puntos b\u00e1sicos acerca de\nlos nomencladores de cuadras. Esta es informaci\u00f3n hist\u00f3rica, pues no todas las\ncalles de Lima tuvieron siempre el mismo nombre. Juan Bromley en su libro<a href=\"https:\/\/www.munlima.gob.pe\/images\/las-viejas-calles-de-lima.pdf\"> <em>Las viejas calles de Lima<\/em><\/a>,\nterminado en 1962, cuenta que cien a\u00f1os antes, una decisi\u00f3n municipal sell\u00f3 la\nhistoria de los caminos de la capital.<\/p>\n\n\n\n<p>Afianzar el sentimiento\npatri\u00f3tico fue la punta de lanza que llev\u00f3 a las autoridades a colocar nombres\nde departamentos y provincias del Per\u00fa a calles y cuadras lime\u00f1as. Sin embargo,\neste proceso tom\u00f3 tiempo, porque exist\u00edan ya designaciones originadas y\nacogidas por los vecinos. Ese pues, fue el seno de ideaci\u00f3n de muchos de los\nnombres: el ingenio de la gente.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Era com\u00fan asignarle a\nlas calles nombres por apodos como Matasiete, Comesebo o Pilitricas; por\noficios, como Colchoneros, Espaderos o Mondongueras; por establecimientos de\nasistencia social, con calles como Divorciadas, Hu\u00e9rfanos o Pobres; por nombres\nzool\u00f3gicos, como Patos, Mono, Gallinacitos o Borricos. Estas son solo algunas\nde las veintisiete formas de asignaci\u00f3n de nombre que estableci\u00f3 Bromley, quien\nelabor\u00f3 un detallado registro de la nomenclatura urbana de Lima vigente en el\na\u00f1o 1861.&nbsp;<\/p>\n\n\n\n<p>Sin lugar a dudas, los\nnombres astron\u00f3micos de la urbanizaci\u00f3n La Luz son posteriores al siglo XIX;\nprimero, porque uno de los homenajeados, el planeta enano Plut\u00f3n, fue descubierto\nen 1930 y; segundo, porque no hay rastros previos de inter\u00e9s por el&nbsp; uso\nde este tipo de nombres. Nivel de atractivo, que a la fecha, es bastante\nopuesto; ya que el Cercado de Lima no es el \u00fanico distrito que cuenta con estos\nnombres en sus calles: Villa Mar\u00eda del Triunfo, Santiago de Surco, San Mart\u00edn\nde Porres y Ate cuentan tambi\u00e9n con urbanizaciones c\u00f3smicas y mitol\u00f3gicas\nenteras.&nbsp;<\/p>\n\n\n\n<p>Las nomenclaturas no\nson inamovibles, todo depende de la iniciativa popular. En parte, se conserva\nese sistema artesanal previo a la independencia del Per\u00fa, en el que<a href=\"https:\/\/www.youtube.com\/watch?v=OMPudkSuw8Y\"> los nombres eran\nproductos de la vida cotidiana<\/a>, o las afecciones o\ninclinaciones de los vecinos. \u00bfAlguna vez te has preguntado cu\u00e1l fue el origen\nde la calle, avenida o jir\u00f3n en el que vives?\u00bfo de las calles, avenidas o\njirones por los que transitas? M\u00e1s de uno lo ha hecho.<\/p>\n\n\n\n<p>Gonzalo Portocarrero, en su columna <a href=\"https:\/\/elcomercio.pe\/opinion\/columnistas\/nombres-calles-gonzalo-portocarrero-noticia-lima-calles-avenidas-479334-noticia\/\">Los nombres de las calles<\/a>, pone su mirada en\nla avenida Los Conquistadores, que guarda una particularidad probablemente poco\nnotada: atribuirle ese nombre a una v\u00eda principal entra\u00f1a una identificaci\u00f3n con\nla tropa de invasores del Tahuantinsuyo. De ah\u00ed que se considere al distrito\ncomo ajeno a la propuesta nacional promovida en 1862, y esta caracter\u00edstica\npodr\u00eda ser llevada a sus habitantes primigenios, Siguiendo esa l\u00f3gica, \u00bfqu\u00e9\nparticularidad podr\u00edan esconder los residentes que admitieron las\ndenominaciones gal\u00e1cticas?&nbsp;&nbsp;<\/p>\n\n\n\n<p>Cada nombre guarda una historia y cada\nhistoria una memoria que, en muchos casos, parece escurrirse. Al actor y ex\nconductor del programa A la vuelta de la esquina, Gonzalo Torres <a href=\"https:\/\/redaccion.lamula.pe\/2012\/01\/22\/detras-de-una-direccion-un-poco-de-historia-en-las-calles-limenas\/admin\/\">le pareci\u00f3 una excelente idea el\ncolocar en los carteles de las calles la historia del nombre<\/a>. Se\u00f1al\u00f3 adem\u00e1s que\naportar\u00eda en la recuperaci\u00f3n de la memoria del peruano, esto en referencia a\ncuadras emblem\u00e1ticas, claro est\u00e1; no obstante, ponerle un cartelito a esas\ncallecitas de nombres singulares no deja de ser un significante \u2014aunque tal vez\nintrascendente\u2014 aporte, que curiosos transe\u00fantes agradecer\u00edan.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empiezas por Marte, y si recorres tres cuadras de frente y doblas a la derecha en la perpendicular, has llegado a Urano. Treinta pasos m\u00e1s y un giro a la izquierda, est\u00e1s en J\u00fapiter \u2014una calle tan p\u00e1rvula que contradice las dimensiones del planeta m\u00e1s grande del sistema solar\u2014, cuyo final es la tercera cuadra [&hellip;]<\/p>\n","protected":false},"author":173,"featured_media":9073,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[316,34,314],"tags":[344,91],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/9072"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/173"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=9072"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/9072\/revisions"}],"predecessor-version":[{"id":9074,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/9072\/revisions\/9074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/9073"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=9072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=9072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=9072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}