{"id":9721,"date":"2021-07-15T02:53:54","date_gmt":"2021-07-15T07:53:54","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=9721"},"modified":"2021-07-15T02:54:07","modified_gmt":"2021-07-15T07:54:07","slug":"situacion-de-la-donacion-de-sangre-durante-la-pandemia","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/situacion-de-la-donacion-de-sangre-durante-la-pandemia\/","title":{"rendered":"Situaci\u00f3n de la donaci\u00f3n de sangre durante la pandemia"},"content":{"rendered":"\n<p style=\"text-align:left\">En los hospitales, se reportan a diario v\u00edctimas de accidentes de tr\u00e1nsito, quemaduras, pacientes con cardiopat\u00edas o alg\u00fan tipo de c\u00e1ncer, gestantes en riesgo y personas que sufren complicaciones en sus cirug\u00edas. Todos ellos necesitan transfusiones de sangre para poder sobrevivir. La falta de donantes dificulta que estos casos tengan un buen final.&nbsp;<\/p>\n\n\n\n<p>Seg\u00fan informaci\u00f3n del doctor <a href=\"https:\/\/www.gob.pe\/institucion\/minsa\/funcionarios\/33967-juan-antonio-almeyda-alcantara\" class=\"ek-link\">Juan Almeyda Alc\u00e1ntara<\/a>, director general de Donaciones, Trasplantes y Banco de Sangre del Ministerio de Salud (MINSA) y, de acuerdo a las estad\u00edsticas  del 2019, solo uno de cada cien peruanos dona sangre. Adem\u00e1s, para una poblaci\u00f3n como la peruana, el porcentaje de donantes voluntarios deber\u00eda, como m\u00ednimo, duplicarse y realizarse en forma peri\u00f3dica.<\/p>\n\n\n\n<p>En la actualidad, el Per\u00fa no dispone de una cultura de donaci\u00f3n voluntaria, es decir, la que se realiza desinteresadamente sin favorecer a una persona en particular y sin ninguna expectativa de retribuci\u00f3n econ\u00f3mica o de otro tipo. El Dr. Oscar Roca Valencia, jefe del Banco de Sangre del <a href=\"https:\/\/www.hejcu.gob.pe\/\" class=\"ek-link\">Hospital Casimiro Ulloa<\/a>, en entrevista para este medio, afirm\u00f3:&nbsp;<\/p>\n\n\n\n<p style=\"text-align:center\"><em>\u201cEste concepto de que la gente no quiere donar parte de algo que es inherente al ser humano. La vida siempre ha sido un bien preciado y muchas veces la ausencia de vida se atribu\u00eda a la p\u00e9rdida del l\u00edquido elemento que permite vivir, que era la sangre. Cambiar ese chip implica un cambio de conducta en la poblaci\u00f3n, eso es lo que hay que cambiar. Principalmente la donaci\u00f3n de sangre tiene que quitar ese chip.\u201d<\/em><br><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"684\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/07\/donaci\u00f3n-1024x684.jpg\" alt=\"\" class=\"wp-image-9722\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/07\/donaci\u00f3n-1024x684.jpg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/07\/donaci\u00f3n-300x200.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/07\/donaci\u00f3n-768x513.jpg 768w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/07\/donaci\u00f3n.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Fuente: Instituto Nacional de Salud del Ni\u00f1o San Borja (INSNSB)<\/figcaption><\/figure>\n\n\n\n<p><strong>Donaci\u00f3n de sangre en tiempos de pandemia<\/strong><\/p>\n\n\n\n<p>Desde que inici\u00f3 el estado de emergencia el pasado15 de marzo del 2020,&nbsp; las donaciones de sangre en el <a href=\"http:\/\/www.insnsb.gob.pe\/\" class=\"ek-link\">Instituto Nacional de Salud del Ni\u00f1o San Borja<\/a> cayeron en m\u00e1s del 70%. La necesidad de donaci\u00f3n de sangre es permanente para los pacientes con leucemia, cardiopat\u00edas cong\u00e9nitas y grandes quemaduras. Mientras que los pacientes que m\u00e1s demanda de sangre y plaquetas requieren son los de trasplante de m\u00e9dula \u00f3sea y cardiovascular.<\/p>\n\n\n\n<p>Muchas personas temen ir a un hospital y contagiarse por el Covid-19. Es por eso que esta instituci\u00f3n ha implementado dos estrategias: \u00abDonam\u00f3vil\u00bb, el cual va al domicilio del donante que se registra previamente al correo del banco de sangre, hace la donaci\u00f3n al frente de su domicilio y, posteriormente, todas las unidades regresan al banco de sangre. La otra estrategia que se implement\u00f3 son las \u00abUnidades M\u00f3viles\u00bb para los donantes de plaquetas. Estas unidades salen del instituto al domicilio del donante de plaquetas, es tra\u00eddo al banco de sangre, hace su donaci\u00f3n y se le retorna nuevamente a su domicilio.&nbsp;<\/p>\n\n\n\n<p>Bajo el lema de \u00abAma, dona, vive\u00bb se impulsan campa\u00f1as masivas de donaci\u00f3n de sangre alrededor de la ciudad, sin embargo, no tienen mucho \u00e9xito. Los ciudadanos interesados pueden acercarse al banco de sangre de la instituci\u00f3n o a la carpa ubicada en el <a href=\"http:\/\/larambla.pe\/mall\/san-borja\/\" class=\"ek-link\">C.C La Rambla de San Borja<\/a> a realizar su donaci\u00f3n de lunes a domingo desde las 9 am hasta las 6 pm.<\/p>\n\n\n\n<p><strong>\u00bfPor qu\u00e9 se dice que un donante puede salvar la vida de hasta 3 personas?<\/strong><\/p>\n\n\n\n<p>Los 450 mililitros de cada extracci\u00f3n de sangre tienen tres componentes b\u00e1sicos: gl\u00f3bulos rojos, plasma y plaquetas, estos se separan y cada uno de ellos se destina para diferentes fines concretos.<\/p>\n\n\n\n<p>En palabras del Dr. Roca Valencia, las sangre debe pasar por un proceso antes de ser utilizada. <em>\u201cNo se recomienda su uso inmediato sino por lo menos 24 o 48 horas despu\u00e9s porque hay que dividirla, o sea fraccionarla, que se refrigere y poder utilizarla, completar todas las pruebas. (&#8230;) No necesariamente estas tres partes van al mismo paciente por eso se dice que una donaci\u00f3n puede salvar hasta tres vidas\u201d<\/em> agreg\u00f3.<\/p>\n\n\n\n<p>Para donar sangre se necesita gozar de buena salud, presentar un documento de identificaci\u00f3n, tener entre 18 a 65 a\u00f1os de edad y pesar m\u00e1s de 50 kg. Las personas pueden donar despu\u00e9s de un a\u00f1o de haberse realizado tatuajes o perforaciones. La frecuencia de donaci\u00f3n es en hombres cada 3 meses y en mujeres, cada 4 meses.<\/p>\n\n\n\n<p>Con la llegada de la pandemia, muchos de los mitos respecto a la donaci\u00f3n de sangre se han intensificado. Algunas personas creen que pueden debilitarse, contraer anemia, sida y hasta temen contagiarse de Covid-19. Sin embargo, el dr. Roca Valencia desmiente estas afirmaciones.<\/p>\n\n\n\n<p style=\"text-align:center\"><em>\u201cEl covid no se transmite por la sangre, se transmite por las secreciones nasales, por las gotitas que uno hace al hablar, por eso se transmite. Si nos cubrimos bien nariz, boca y ojos, no va a haber ning\u00fan problema.\u201d<\/em>&nbsp;<\/p>\n\n\n\n<p>Al Hospital de Emergencias Casimiro Ulloa ingresan diariamente v\u00edctimas de accidentes de tr\u00e1nsito y pacientes con operaciones de suma urgencia. El arribo de la pandemia trajo consigo una disminuci\u00f3n preocupante de donantes para este banco de sangre. Actualmente, apenas cuentan con uno o ning\u00fan donante por cada hora. La desinformaci\u00f3n y el temor respecto al tema son las principales causas de esta situaci\u00f3n.<\/p>\n\n\n\n<p><strong>\u00abHemoBus\u00bb, una iniciativa creada para incentivar las donaciones de sangre<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"472\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/07\/3-1024x472.jpeg\" alt=\"\" class=\"wp-image-9723\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/07\/3-1024x472.jpeg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/07\/3-300x138.jpeg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/07\/3-768x354.jpeg 768w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/07\/3.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Fuente: Patricia Segil Baltazar<\/figcaption><\/figure>\n\n\n\n<p>El hospital Casimiro Ulloa en alianza con la Asociaci\u00f3n de Donantes de Sangre del Per\u00fa y la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Distrito_de_Santiago_de_Surco\" class=\"ek-link\">Municipalidad de Surco<\/a> impulsa una campa\u00f1a de donaci\u00f3n m\u00f3vil denominada \u00abHemoBus\u00bb. El pasado lunes 5 de julio empez\u00f3 sus actividades en la cuadra 52 de la avenida Benavides.&nbsp;<\/p>\n\n\n\n<p>Su objetivo es salir a buscar donantes para mantener las reservas del banco de sangre en condiciones aceptables y promover la cultura de donaci\u00f3n voluntaria a\u00fan en el contexto de pandemia. Los interesados pueden acudir todos los mi\u00e9rcoles y s\u00e1bados de cada mes. Las condiciones de bioseguridad est\u00e1n garantizadas.<\/p>\n\n\n\n<p>Donar sangre refuerza nuestro sistema inmunol\u00f3gico, incentiva la creaci\u00f3n de gl\u00f3bulos rojos, previene problemas de presi\u00f3n arterial y cardiaco. Asimismo, te da la oportunidad de realizarte descartes de anemia, VIH, hepatitis, entre otros.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/07\/2-1024x683.jpg\" alt=\"\" class=\"wp-image-9724\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/07\/2-1024x683.jpg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/07\/2-300x200.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/07\/2-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Fuente: Patricia Segil Baltazar<\/figcaption><\/figure>\n\n\n\n<p>Si est\u00e1s en condiciones de donar, no esperes a que te lo pidan. Ac\u00e9rcate al establecimiento de salud m\u00e1s cercano a tu domicilio. Y recuerda que donar sangre es un gran acto de solidaridad. Salvar vidas est\u00e1 en nuestras venas.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los hospitales, se reportan a diario v\u00edctimas de accidentes de tr\u00e1nsito, quemaduras, pacientes con cardiopat\u00edas o alg\u00fan tipo de c\u00e1ncer, gestantes en riesgo y personas que sufren complicaciones en sus cirug\u00edas. Todos ellos necesitan transfusiones de sangre para poder sobrevivir. La falta de donantes dificulta que estos casos tengan un buen final.&nbsp; Seg\u00fan informaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":172,"featured_media":9728,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[314,333,482],"tags":[1418,124],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/9721"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/172"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=9721"}],"version-history":[{"count":5,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/9721\/revisions"}],"predecessor-version":[{"id":9731,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/9721\/revisions\/9731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/9728"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=9721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=9721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=9721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}