{"id":9733,"date":"2021-08-13T16:06:50","date_gmt":"2021-08-13T21:06:50","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=9733"},"modified":"2021-08-13T16:06:50","modified_gmt":"2021-08-13T21:06:50","slug":"san-juan-de-miraflores-ya-cuenta-con-planta-de-oxigeno-medicinal","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/san-juan-de-miraflores-ya-cuenta-con-planta-de-oxigeno-medicinal\/","title":{"rendered":"San Juan de Miraflores ya cuenta con planta de ox\u00edgeno medicinal"},"content":{"rendered":"\n<p>El pasado <strong>14 de julio<\/strong> se inaugur\u00f3 la primera <strong>planta de ox\u00edgeno <\/strong>\u00abBel\u00e9n\u00bb en la <strong>parroquia Ni\u00f1o Jes\u00fas<\/strong> en el sector conocido como Ciudad de Dios en <strong>San Juan de Miraflores.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"766\" height=\"1024\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/plantaoxigeno-766x1024.jpg\" alt=\"\" class=\"wp-image-10358\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/plantaoxigeno-766x1024.jpg 766w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/plantaoxigeno-224x300.jpg 224w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/plantaoxigeno-768x1027.jpg 768w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/plantaoxigeno.jpg 1532w\" sizes=\"(max-width: 766px) 100vw, 766px\" \/><figcaption>Fuente: Municipalidad de Lima<\/figcaption><\/figure>\n\n\n\n<p>Esta iniciativa vio la luz gracias a la colaboraci\u00f3n de diversas empresas privadas y las gestiones de los representantes de la municipalidad de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Distrito_de_San_Juan_de_Miraflores\" class=\"ek-link\">San Juan de Miraflores<\/a> junto a la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Di%C3%B3cesis_de_Lur%C3%ADn\" class=\"ek-link\">Di\u00f3cesis de Lur\u00edn<\/a>. La Asociaci\u00f3n de la Bienaventuranzas, instituci\u00f3n que pertenece a esta di\u00f3cesis, se encargar\u00e1 de mantener operativa la planta y la municipalidad, de la log\u00edstica para trasladar el ox\u00edgeno hacia los vecinos m\u00e1s vulnerables. Dicha planta producir\u00e1 48 balones de 10 metros c\u00fabicos al d\u00eda completamente gratis en beneficio de m\u00e1s de 400 mil habitantes del distrito de Lima Sur.<\/p>\n\n\n\n<p>La inauguraci\u00f3n cont\u00f3 con la presencia de la alcaldesa del distrito, Cristina Nina y el representante de la <a href=\"https:\/\/asociacionbienaventuranzas.org.pe\/\" class=\"ek-link\">Asociaci\u00f3n de las Bienaventuranzas<\/a>, padre Omar Buenaventura. Por otro lado, las empresas privadas <a href=\"https:\/\/www.scotiabank.com.pe\/\" class=\"ek-link\">Scotiabank<\/a> y <a href=\"https:\/\/www.unicon.com.pe\/\" class=\"ek-link\">Unicon<\/a> tambi\u00e9n estuvieron presentes gracias a la participaci\u00f3n de Manuel Silva y del ingeniero Mariano Ramos. La alcaldesa remarc\u00f3 \u00e9nfasis en el apoyo recibido por el sector privado. <em>\u201cLo importante que son estos trabajos articulados entre la iglesia, instituciones privadas y la poblaci\u00f3n en general. Tenemos que estar juntos para afrontar estos dif\u00edciles momentos y dar soluciones. Es reconfortante anunciarles que van a contar con una planta de oxigeno gratuita y que va a poder seguir salvando vidas.\u201d<\/em>, coment\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/plantaoxigeno1-1024x768.jpg\" alt=\"\" class=\"wp-image-10359\" srcset=\"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/plantaoxigeno1-1024x768.jpg 1024w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/plantaoxigeno1-300x225.jpg 300w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/plantaoxigeno1-768x576.jpg 768w, https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-content\/uploads\/2021\/08\/plantaoxigeno1.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Fuente: Municipalidad de San Juan de Miraflores<\/figcaption><\/figure>\n\n\n\n<p>Las cifras de impacto por en covid-19 en nuestro pa\u00eds han empezado a disminuir como resultado de la campa\u00f1a de vacunaci\u00f3n. Sin embargo, muchos compatriotas a\u00fan experimentan una demanda insatisfecha de ox\u00edgeno. Por ello, el\u00a0Grupo <a href=\"https:\/\/www.unacem.com.pe\/\" class=\"ek-link\">Unacem<\/a>, l\u00edder en el sector cementero, ha enfocado sus esfuerzos en apoyar a la poblaci\u00f3n vulnerable de las \u00e1reas de influencia de sus operaciones, aspirando a beneficiar a m\u00e1s de 48,500 vecinos de San Juan de Miraflores y Villa Mar\u00eda del triunfo en un a\u00f1o.<\/p>\n\n\n\n<p>Finalmente, la cementera\u00a0Unacem, en coordinaci\u00f3n con la Direcci\u00f3n de Redes Integrales de Salud (DIRIS) de Lima Sur, instalar\u00e1 una cuarta planta en el Centro Materno Infantil en la zona de Jos\u00e9 G\u00e1lvez, en Villa Mar\u00eda del Triunfo. Esta donaci\u00f3n ser\u00e1 puesta en marcha por la Asociaci\u00f3n Unacem, equipo de responsabilidad social del Grupo.<\/p>\n\n\n\n<p>&nbsp;En\nlo que concierne a Lima Metropolitana, el Minsa instal\u00f3 36 plantas operativas\nde ox\u00edgeno medicinal que producen alrededor de 489 metros c\u00fabicos por hora;\nmientras que el Callao cuenta con siete plantas que producen 164 metros c\u00fabicos\npor hora. Entre ambas jurisdicciones se producen 24.17 toneladas por d\u00eda.&nbsp;\n&nbsp;<\/p>\n\n\n\n<p>El\nesfuerzo que desarrolla el Minsa se orienta a cerrar la brecha de ox\u00edgeno en el\nnivel hospitalario y ampliar el acceso a la oxigenaci\u00f3n temprana en el primer\nnivel de atenci\u00f3n, para as\u00ed cubrir la necesidad de la poblaci\u00f3n afectada por el\ncovid-19.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 14 de julio se inaugur\u00f3 la primera planta de ox\u00edgeno \u00abBel\u00e9n\u00bb en la parroquia Ni\u00f1o Jes\u00fas en el sector conocido como Ciudad de Dios en San Juan de Miraflores. Esta iniciativa vio la luz gracias a la colaboraci\u00f3n de diversas empresas privadas y las gestiones de los representantes de la municipalidad de San [&hellip;]<\/p>\n","protected":false},"author":172,"featured_media":10360,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[314,482,1],"tags":[],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/9733"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/172"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=9733"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/9733\/revisions"}],"predecessor-version":[{"id":10361,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/9733\/revisions\/10361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/10360"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=9733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=9733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=9733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}