{"id":9822,"date":"2021-07-22T02:49:38","date_gmt":"2021-07-22T07:49:38","guid":{"rendered":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/?p=9822"},"modified":"2021-07-22T02:52:36","modified_gmt":"2021-07-22T07:52:36","slug":"realmente-la-vida-digital-contamina-menos","status":"publish","type":"post","link":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/realmente-la-vida-digital-contamina-menos\/","title":{"rendered":"\u00bfRealmente la vida digital contamina menos?"},"content":{"rendered":"\n<p><br><\/p>\n\n\n\n<p>A principios de marzo del a\u00f1o pasado, la NASA y la Agencia Espacial Europea publicaron im\u00e1genes satelitales de China, en donde se muestra la disminuci\u00f3n de la contaminaci\u00f3n atmosf\u00e9rica durante el confinamiento por la crisis sanitaria.\u00a0<br><\/p>\n\n\n\n<p>En consecuencia a lo anterior, distintos medios se\u00f1alaron los beneficios de la cuarentena, y la reducci\u00f3n del consumo de combustibles f\u00f3siles. Sin embargo, no mencionaron la contraparte a esto: el excesivo incremento del uso del internet.<br><\/p>\n\n\n\n<p>El internet est\u00e1 presente en la mayor\u00eda de nuestras actividades, sobre todo durante el confinamiento, y este es el que ha impulsado el incremento de la contaminaci\u00f3n digital. Pero, para tener una idea m\u00e1s clara sobre c\u00f3mo se produce la contaminaci\u00f3n digital, se debe mencionar los medios por los que se da.&nbsp;&nbsp;<br><\/p>\n\n\n\n<p><strong>Almacenamiento de datos<\/strong><\/p>\n\n\n\n<p>Si bien tenemos una idea del internet como un servicio intangible, este presenta una parte material desde la cual se gestiona la informaci\u00f3n: los centros de datos. Los centros de almacenamiento de datos son los corazones del internet, y tambi\u00e9n un productor del m\u00e1s del 2% de CO2 que hay en el mundo.&nbsp;<br><\/p>\n\n\n\n<p>Seg\u00fan un informe de la ONG Greenpeace, el CO2 que produce el mundo digital es superior al del transporte a\u00e9reo. Adem\u00e1s, The Guardian revel\u00f3 que las cifras exactas de la emisi\u00f3n de gases invernaderos por el medio digital es de 300 millones de toneladas al a\u00f1o.&nbsp;<br><\/p>\n\n\n\n<p>Estas cifras se suman al de la creciente utilizaci\u00f3n de energ\u00eda el\u00e9ctrica para la refrigeraci\u00f3n de los datos en la nube. Aunque un usuario en particular no presente mayor impacto en la contaminaci\u00f3n digital, la cantidad excesiva de estos y el uso desproporcionado del internet contribuyen a la producci\u00f3n desmesurada de agentes contaminantes.<\/p>\n\n\n\n<p><strong>E-mails y redes sociales<\/strong><\/p>\n\n\n\n<p>Las actividades en redes sociales son una de las m\u00e1s perjudiciales al medio ambiente. Se calcula que la reproducci\u00f3n de videos en l\u00ednea equivale al 1% de las emisiones de gas de efecto invernadero. Del mismo modo, subir fotos a Instagram, enviar mensajes por Whatsapp o realizar una publicaci\u00f3n por Facebook tambi\u00e9n tiene repercusiones en el ecosistema.<br><\/p>\n\n\n\n<p>Incluso el uso del correo electr\u00f3nico es perjudicial en grandes escalas. Seg\u00fan Greenpeace, un e-mail con un archivo adjunto es equivalente en el desgaste energ\u00e9tico de dejar una bombilla encendida durante una hora. Teniendo en cuenta que actualmente los e-mails son en su mayor\u00eda usados para el traslado de archivos, el resultado en conjunto es alarmante.&nbsp;&nbsp;<br><\/p>\n\n\n\n<p><strong>Las plataformas de streaming<\/strong><\/p>\n\n\n\n<p>Los servicios de streaming se encuentran liderando la lista de plataformas digitales m\u00e1s contaminantes, muy por arriba de las redes sociales. Los informes de Greenpeace indican que un 34% de los da\u00f1os del mundo digital al medio ambiente pertenecen al uso de estas plataformas.<\/p>\n\n\n\n<p>Por su parte, la revista Rolling Stone public\u00f3 un art\u00edculo en donde se\u00f1ala c\u00f3mo la aparici\u00f3n de plataformas musicales de streaming fueron las detonadoras de la producci\u00f3n excesiva de gases de efecto invernadero. La producci\u00f3n de los gases oscila anualmente entre los 200 y 350 millones de kilogramos.<br><\/p>\n\n\n\n<p>Por otro lado, Shift Project, ONG francesa, declar\u00f3, que las plataformas de pel\u00edculas como Netflix, Amazon Prime y Hulu son otro gran peligro para el medio ambiente. El informe de la ONG indic\u00f3 que media hora viendo Netflix genera las mismas emisiones que conducir durante 6 kil\u00f3metros.&nbsp;<\/p>\n\n\n\n<p><strong>Desechos tecnol\u00f3gicos<\/strong><\/p>\n\n\n\n<p>Los aparatos electr\u00f3nicos se encuentran en constante actualizaci\u00f3n. Celulares, laptops, computadoras; todos ellos se fabrican cada a\u00f1o, adquiriendo nuevas caracter\u00edsticas o funciones. Sin embargo, la fabricaci\u00f3n de los productos y el desecho de los modelos pasados, le pas\u00f3 factura al ecosistema.<br><\/p>\n\n\n\n<p>Tan solo para fabricar una computadora se necesitan 240 kilos de combustible f\u00f3sil, 22 kilos de productos qu\u00edmicos y 1,5 toneladas de agua. Si de por s\u00ed los implementos en la elaboraci\u00f3n de los aparatos tecnol\u00f3gicos son contaminantes, el desecho de estos es a\u00fan m\u00e1s perjudicial.<\/p>\n\n\n\n<p>El Programa para el Medio Ambiente de las Naciones Unidas (PNUMA)&nbsp; calcul\u00f3 cerca de 50 millones de toneladas de desechos electr\u00f3nicos al a\u00f1o. Entre ellos se encuentran metales t\u00f3xicos como el mercurio, plomo o ars\u00e9nico, los cuales son nocivos tanto para el ser humano como para el medio ambiente.<br><\/p>\n\n\n\n<p><strong>\u00bfQ\u00fae podemos hacer?&nbsp;<\/strong><\/p>\n\n\n\n<p>Empresas como Google, Apple y Facebook han tomado las medidas respectivas, incrementando el uso de energ\u00edas \u2018limpias\u2019 o renovables. Sin embargo, Shift Project aconseja a cada usuario ser responsable con el consumo virtual.&nbsp;<br><\/p>\n\n\n\n<p>Si bien el confinamiento nos ha obligado a realizar la mayor\u00eda de nuestras actividades de forma virtual, a\u00fan es posible regularlas y, de este modo, reducir el impacto negativo en la naturaleza.&nbsp;<br><\/p>\n\n\n\n<p>Estas son alguna de las pr\u00e1cticas que puedes realizar para disminuir la contaminaci\u00f3n digital:<\/p>\n\n\n\n<ul><li>Al usar plataformas de streaming, asegurarse de estar conectado a una red de fibra \u00f3ptica. No utilizar los datos m\u00f3viles.&nbsp;<\/li><li>Limpiar la bandeja de entrada del correo electr\u00f3nico.<\/li><li>Gestionar el tiempo de uso de las redes sociales.<\/li><li>No cambiar de equipos electr\u00f3nicos frecuentemente. Tener en cuenta el periodo de durabilidad y donar los dispositivos que est\u00e9n en buen estado..<\/li><li>Tratar de utilizar webs ecol\u00f3gicas o que presenten beneficios al medio ambiente. Un ejemplo ser\u00eda el buscador web \u2018Ecosia\u2019.<\/li><\/ul>\n\n\n\n<p>La aparici\u00f3n de la digitalidad ha tra\u00eddo innumerables beneficios a la vida cotidiana. Es responsabilidad tanto de las empresas como de los usuarios ser responsables con su uso, para poder aprovecharlas sin perjuicio alguno.&nbsp;<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A principios de marzo del a\u00f1o pasado, la NASA y la Agencia Espacial Europea publicaron im\u00e1genes satelitales de China, en donde se muestra la disminuci\u00f3n de la contaminaci\u00f3n atmosf\u00e9rica durante el confinamiento por la crisis sanitaria.\u00a0 En consecuencia a lo anterior, distintos medios se\u00f1alaron los beneficios de la cuarentena, y la reducci\u00f3n del consumo de [&hellip;]<\/p>\n","protected":false},"author":176,"featured_media":9823,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[40,325,326],"tags":[156,165],"_links":{"self":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/9822"}],"collection":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/users\/176"}],"replies":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/comments?post=9822"}],"version-history":[{"count":1,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/9822\/revisions"}],"predecessor-version":[{"id":9827,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/posts\/9822\/revisions\/9827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media\/9823"}],"wp:attachment":[{"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/media?parent=9822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/categories?post=9822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medialab.unmsm.edu.pe\/chiqaqnews\/wp-json\/wp\/v2\/tags?post=9822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}